{"id":9291,"date":"2024-09-11T07:31:37","date_gmt":"2024-09-11T10:31:37","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=9291"},"modified":"2024-09-11T07:31:37","modified_gmt":"2024-09-11T10:31:37","slug":"ordenanza-no-1-450","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2024\/09\/11\/ordenanza-no-1-450\/","title":{"rendered":"Ordenanza N\u00ba 1.450"},"content":{"rendered":"\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>Ordenanza N\u00ba 1.450<\/strong><\/p>\n\n\n\n<p><strong>VISTO:<\/strong>\nLa Ordenanza N\u00b0 576<\/p>\n\n\n\n<p><strong>CONSIDERANDO:<\/strong>\n<\/p>\n\n\n\n<p>Que la mencionada normativa, en su\nart. 1, establece la prohibici\u00f3n de realizaci\u00f3n de eventos nocturnos de manera\nconsecutiva, con m\u00fasica y con la concurrencia de gran cantidad de personas en\nla zona c\u00e9ntrica de la ciudad de Nogoy\u00e1.<\/p>\n\n\n\n<p>Que en la zona donde actualmente\nrige la prohibici\u00f3n de realizaci\u00f3n de los eventos mencionados anteriormente, se\nencuentran la gran mayor\u00eda de los bares y comedores de la ciudad, que interesan\nde realizar eventos de diversa \u00edndole que ampl\u00eden la oferta cultural y\ntur\u00edstica que ofrece nuestra ciudad, y se ven actualmente limitados por la\nnormativa existente. <\/p>\n\n\n\n<p>Que desde este cuerpo se viene\ntrabajando en normativa para fortalecer el turismo y todas sus actividades\nconexas en la ciudad de Nogoy\u00e1.<\/p>\n\n\n\n<p>Que la realizaci\u00f3n de eventos tipo\n\u201cCanto Bar\u201d, Pub, noches de arte tem\u00e1ticas, pe\u00f1as y similares, son una oferta\ncultural para un sector de la sociedad que no acostumbra concurrir a boliches,\ndiscotecas o fiestas similares, adem\u00e1s de incrementar el atractivo de\nvisitantes de otras localidades. <\/p>\n\n\n\n<p>Que es necesario regular la\nrealizaci\u00f3n de los eventos mencionados en los considerandos anteriores, de\nmanera que puedan coexistir con la normativa vigente, sin alterar la\ntranquilidad de los vecinos. <\/p>\n\n\n\n<p><strong>Por ello: <\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE\nDEL MUNICIPIO DE NOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON FUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong>\nModif\u00edquese el art. 1\u00b0 de la Ordenanza N\u00b0 576, el cual quedara redactado de la\nsiguiente manera: \u201c<em>Art\u00edculo 1\u00b0: Proh\u00edbase\nla localizaci\u00f3n de Boliches, Confiter\u00edas Bailables o Discotecas, entendi\u00e9ndose\npor tales aquellos establecimientos comerciales donde un alto n\u00famero de\npersonas concurren a bailar, en trasnoche, con expendio de bebidas y m\u00fasica que\npuede ser en vivo o con un DJ, en el \u00e1rea comprendida entre Bv. Sarmiento,\nGdor. Cont\u00edn, Belgrano y Bv. Espa\u00f1a, todas por ambas aceras, salvo que cuente\ncon la conformidad de los vecinos linderos en todo el per\u00edmetro del lote y los\nvecinos de la acera opuesta<\/em>.\u201d<\/p>\n\n\n\n<p><strong>Art\u00edculo 2\u00ba.-<\/strong><strong> <\/strong>Agr\u00e9guese a la Ordenanza N\u00b0 576 el art. 1 bis, que\nquedar\u00e1 redactado de la siguiente manera \u201c<em>Art\u00edculo\n1\u00b0 bis: Respecto a los denominados Cantobar, Pub, Caf\u00e9 Concerts, o similares,\nentendi\u00e9ndose por tales a los bares o restaurantes <\/em><em>donde se\nexpenden bebidas y\/o comidas para consumo en el mismo lugar y donde, como\ncomplemento, se desarrollan reuniones bailables con o sin espect\u00e1culos\nart\u00edsticos\/musicales, los mismos estar\u00e1n habilitados para funcionar dentro y\nfuera de la zona descripta en el art\u00edculo anterior, en tanto cumplan con los\nrequisitos siguientes: <\/em><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><em>Podr\u00e1n funcionar en la modalidad descripta en\n     el presente art\u00edculo hasta las 03 horas, viernes, s\u00e1bado y v\u00edspera de\n     feriados, pudiendo continuar funcionando en la modalidad bar dentro de los\n     horarios de apertura y cierre estipulados en la Ordenanza N\u00b0 558.<\/em><\/li><li><em>Deber\u00e1n contar con un espacio adecuado, que\n     permita la combinaci\u00f3n de mesas y pista de baile de acuerdo a la capacidad\n     del local, como as\u00ed tambi\u00e9n con un espacio adecuado para la actuaci\u00f3n de\n     n\u00fameros art\u00edsticos. <\/em><\/li><li><em>Deber\u00e1n contar con ba\u00f1os en proporci\u00f3n a su\n     capacidad.&nbsp; <\/em><\/li><li><em>Deber\u00e1n disponer de elementos y artefactos\n     en buen funcionamiento para el servicio contra incendio, de acuerdo a las\n     reglamentaciones vigente al efecto.<\/em><em><\/em><\/li><li><em>Deber\u00e1n presentar planos generales y de\n     aislaci\u00f3n ac\u00fastica de acuerdo a lo previsto en el art 5 de la presente\n     ordenanza<\/em><em>.<\/em><\/li><li><em>Deber\u00e1n inscribirse en el \u00e1rea de Comercio de\n     la Municipalidad, o la que en el futuro la reemplace, como pub, cantobar,\n     o la categor\u00eda que establezca el D.E.M.\u201d.<\/em><\/li><\/ol>\n\n\n\n<p><em>Para los locales comerciales comprendidos en el presente art\u00edculo y que\na la fecha de entrada en vigencia est\u00e9n en funcionamiento bajo otra modalidad,\nse les otorgar\u00e1 un plazo de seis (6) meses para adecuarse a la normativa.\u201d<\/em><\/p>\n\n\n\n<p><strong>Art\u00edculo\n3\u00ba.-<\/strong><strong> <\/strong>Modif\u00edquese\nel Art\u00edculo 3\u00b0 de la Ordenanza N\u00b0 576 que quedar\u00e1 redactado de la siguiente\nmanera: \u201c<em>Art\u00edculos 3\u00b0: Queda\nterminantemente prohibido la instalaci\u00f3n de nuevos locales comerciales\ndescriptos en el Art\u00edculo 1\u00b0 en predios o galpones a menos de 300 metros de\nradio de hospitales, sanatorios, cl\u00ednicas privadas, asilos de ancianos etc., y\npara el caso de nuevos locales comerciales descriptos en el Art\u00edculo 1\u00b0 bis, la\ndistancia no podr\u00e1 ser menor a 100 metros.<\/em>\u201d<\/p>\n\n\n\n<p><strong>Art\u00edculo\n4\u00b0.<\/strong><strong> <\/strong>Proc\u00e9dase a la realizaci\u00f3n del texto ordenado de la\nOrdenanza N\u00b0 576 con las modificaciones establecidas en la presente.-<\/p>\n\n\n\n<p><strong>Art\u00edculo\n5\u00b0.<\/strong> De forma.-<\/p>\n\n\n\n<p>\u00a0Nogoy\u00e1, sala de sesiones, 11 de septiembre de 2024.- <\/p>\n\n\n\n<p>Aprobada por unanimidad, en general y en particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modif\u00edquese el art. 1\u00b0 de la Ordenanza N\u00b0 576 y Agr\u00e9guese a la Ordenanza N\u00b0 576 el art. 1 bis<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-9291","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9291"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9291\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}