{"id":9239,"date":"2024-08-14T07:41:50","date_gmt":"2024-08-14T10:41:50","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=9239"},"modified":"2024-08-14T07:41:50","modified_gmt":"2024-08-14T10:41:50","slug":"ordenanza-no-1444","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2024\/08\/14\/ordenanza-no-1444\/","title":{"rendered":"Ordenanza N\u00ba 1444"},"content":{"rendered":"\n<p style=\"text-align:right\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ordenanza N\u00ba 1.444<\/strong><\/p>\n\n\n\n<p><strong>VISTO: <\/strong>La nota\npresentada por la Prof. Marcela Ochoteco, la directora de la Escuela Coral N\u00b0 3\n\u201cJorge Mockert\u201d CUE N\u00b0 300-3365, y,<\/p>\n\n\n\n<p><strong>CONSIDERANDO: <\/strong><\/p>\n\n\n\n<p>Que mediante la nota de referencia, se\nsolita que se declare de Inter\u00e9s Cultural Municipal al Proyecto denominado \u201cEscuelas que cantan: Abre la ventana\u201d\nque conducir\u00e1n las docentes de la Escuela Coral N\u00ba 3 \u201cJorge Mockert\u201d y el \u201c2do Megaconcierto de Ni\u00f1os Cantores<strong>\u201d<\/strong>\nque se realizar\u00e1 en el mes de octubre de 2024, en el que participar\u00e1n los coros\nde la Escuela Coral junto con los ni\u00f1os de los cuartos grados de las escuelas\nprimarias de la nuestra ciudad;<\/p>\n\n\n\n<p>Que a partir de la experiencia realizada\nen el ciclo lectivo 2.023, donde se congregaron las diferentes escuelas\nprimarias y participaron m\u00e1s de 300 ni\u00f1os, se obtuvo un impacto muy positivo en\nla comunidad;<\/p>\n\n\n\n<p>Que el nuevo proyecto plantea una tem\u00e1tica\nliteraria y musical cuyo eje fundamental es \u201cLa Naturaleza y su cuidado\u201d;<\/p>\n\n\n\n<p>Que la propuesta implica un trabajo que\nintegra diferentes \u00e1reas del aprendizaje, como son M\u00fasica, Artes Visuales,\nCiencias Sociales, Ciencias Naturales, Lengua, Matem\u00e1tica, entre otras;<\/p>\n\n\n\n<p>Que esta nueva edici\u00f3n se llevara a\ndelante el viernes 18 de octubre del presente en el Polideportivo Municipal;<\/p>\n\n\n\n<p>Que el objetivo fundamental es el\ndesarrollo de canciones, escenograf\u00eda, y sobre todo incentivar a los ni\u00f1os a\nexpresar sus emociones, fomentando el canto coral, y el sentido de pertenencia\na sus instituciones educativas;<\/p>\n\n\n\n<p>Que, por estos motivos, este Concejo\nDeliberante, entiende fundamental acompa\u00f1ar estas actividades que tanto bien\nhace a nuestra sociedad, y muy especialmente a nuestros ni\u00f1os, declarando de\nInter\u00e9s Cultural Municipal, el segundo Megaconcierto de Ni\u00f1os Cantores;<\/p>\n\n\n\n<p><strong>Por ello<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO\nDELIBERANTE DE LA CIUDAD DE NOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON\nFUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p>ART\u00cdCULO\n1\u00b0.-Decl\u00e1rese de Inter\u00e9s Cultural\nMunicipalal proyecto denominado \u201cEscuelas que cantan: Abre la\nVentana\u201d y el \u201cSegundo Megaconcierto de Ni\u00f1os Cantores\u201d, que se desarrollar\u00e1 el\nd\u00eda 18 de octubre&nbsp; del 2.024 a la hora\n20:30 en las instalaciones del Polideportivo Municipal, con ni\u00f1os de la ciudad\nde Nogoy\u00e1.-<\/p>\n\n\n\n<p><strong>ART\u00cdCULO 2\u00b0.<\/strong>&#8211; De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nogoy\u00e1, Sala de sesiones, 14 de agosto 2024.-<\/p>\n\n\n\n<p>Aprobado por unanimidad, en general y en particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decl\u00e1rese de Inter\u00e9s Cultural Municipal al proyecto denominado \u201cEscuelas que cantan: Abre la Ventana\u201d y el \u201cSegundo Mega Concierto de Ni\u00f1os Cantores\u201d,  en las instalaciones del Polideportivo Municipal, con ni\u00f1os de la ciudad de Nogoy\u00e1.-<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-9239","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9239"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9239\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}