{"id":9145,"date":"2024-06-19T08:13:56","date_gmt":"2024-06-19T11:13:56","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=9145"},"modified":"2024-06-19T08:13:56","modified_gmt":"2024-06-19T11:13:56","slug":"ordenanza-no-1-431","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2024\/06\/19\/ordenanza-no-1-431\/","title":{"rendered":"Ordenanza N\u00ba 1431"},"content":{"rendered":"\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n\n\n\n<p><strong>VISTO<\/strong>: El Acuerdo de Reconocimiento, Consolidaci\u00f3n y Pago de Deuda\npor Contribuciones Patronales suscripto por la Municipalidad de Nogoy\u00e1 y la Caja\nde Jubilaciones y Pensiones de Nogoy\u00e1; y,<\/p>\n\n\n\n<p><strong>CONSIDERANDO<\/strong>: <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que en fecha 22\/04\/24 se suscribe el Convenio de\nreferencia donde las partes consolidan y acuerdan el pago de deuda en concepto\nde contribuciones patronales de la Municipalidad a la Caja de Jubilaciones y\nPensiones;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que se consolida la deuda en la suma de PESOS CIENTO\nNOVENTA MILLONES DIECINUEVE MIL NOVECIENTOS DIECIOCHO CON CINCUENTA Y TRES\nCENTAVOS ($190.019.918,53.-), la que comprende las contribuciones patronales correspondientes a los per\u00edodos junio de 2023 a diciembre de\n2023, S.A.C. 1er y 2do semestre de 2023 del personal de Planta Permanente y\nper\u00edodo diciembre de 2023 del personal de Planta Transitoria;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que el capital consolidado ser\u00e1 abonado con un plazo de\nDOS (2) a\u00f1os a partir del 22 de julio de 2024, en VEINTICUATRO (24) cuotas\nmensuales y consecutivas con vencimiento los d\u00edas 22 de cada mes y dem\u00e1s\ncondiciones establecidas en el Convenio girado por el Departamento Ejecutivo\nMunicipal;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, a los fines de dar cumplimiento a la normativa\nvigente, es necesario que este Cuerpo Deliberativo apruebe el Convenio de\nreferencia a los fines de su ejecuci\u00f3n. <\/p>\n\n\n\n<p><strong>Por ello<\/strong>: <\/p>\n\n\n\n<p style=\"text-align:center\">EL CONCEJO\nDELIBERANTE DEL MUNICIPIO DE NOGOY\u00c1<\/p>\n\n\n\n<p style=\"text-align:center\">SANCIONA CON\nFUERZA DE<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>ART\u00cdCULO 1\u00ba.-<\/strong>Apru\u00e9bese el <strong>\u201cACUERDO\nDE RECONOCIMIENTO, CONSOLIDACI\u00d3N Y PAGO DE DEUDA POR CONTRIBUCIONES\nPATRONALES\u201d, <\/strong>firmado en fecha 22 de abril de 2024 por el Departamento\nEjecutivo Municipal y las Autoridades de la Caja Municipal de Jubilaciones y\nPensiones de Nogoy\u00e1, por la suma de PESOS CIENTO NOVENTA MILLONES DIECINUEVE\nMIL NOVECIENTOS DIECIOCHO CON CINCUENTA Y TRES CENTAVOS ($190.019.918,53.-). A\ndicho monto se le adicionar\u00e1, consolidando la suma restante de los intereses\ndel per\u00edodo de espera.-<\/p>\n\n\n\n<p><strong>ART\u00cdCULO 2\u00ba.-<\/strong>Autor\u00edcese al Departamento Ejecutivo Municipal a\ngarantizar el <strong>\u201cACUERDO DE\nRECONOCIMIENTO, CONSOLIDACI\u00d3N Y PAGO DE DEUDA POR CONTRIBUCIONES PATRONALES\u201d<\/strong>\nal que refiere el art\u00edculo precedente, con los ingresos que reciba la\nMunicipalidad de Nogoy\u00e1 por la Coparticipaci\u00f3n de Impuestos Provinciales.-<\/p>\n\n\n\n<p><strong>ART\u00cdCULO 3\u00ba.-<\/strong>De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nogoy\u00e1, sala de\nsesiones, 19 de junio de 2024.-<\/p>\n\n\n\n<p>Aprobado por unanimidad, en\ngeneral y en particular.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprobaci\u00f3n del Acuerdo con la Caja de Jubilaciones y Pensiones Municipal.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-9145","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9145"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/9145\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}