{"id":8767,"date":"2024-05-08T09:58:25","date_gmt":"2024-05-08T12:58:25","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=8767"},"modified":"2024-05-08T09:58:25","modified_gmt":"2024-05-08T12:58:25","slug":"ordenanza-no-1425","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2024\/05\/08\/ordenanza-no-1425\/","title":{"rendered":"Ordenanza N\u00ba 1425"},"content":{"rendered":"\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n\n\n\n<p><strong>VISTO:<\/strong>\n<\/p>\n\n\n\n<p>Las reiteradas solicitudes de personas\nque carecen de dominio o posesi\u00f3n de inmuebles, de certificados de domicilio o\npermisos de uso al Departamento Ejecutivo Municipal; y,<\/p>\n\n\n\n<p><strong>CONSIDERANDO:<\/strong><\/p>\n\n\n\n<p>Que es habitual la solicitud de vecinos\nal Departamento Ejecutivo Municipal de un certificado de domicilio o permiso de\nuso de inmuebles a fin de obtener el suministro de servicio el\u00e9ctrico, seg\u00fan lo\nestablecido por el art. 1 del Reglamento de ENERSA. <\/p>\n\n\n\n<p>Que es un deber del estado municipal\nprevenir los asentamientos ilegales en calles p\u00fablicas, tierras fiscales y\ndem\u00e1s inmuebles del estado Nacional, Provincial o Municipal.<\/p>\n\n\n\n<p>Que es necesario establecer criterios\npara el otorgamiento responsable de los certificados mencionados anteriormente.<\/p>\n\n\n\n<p><strong>Por ello:<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE DEL MUNICIPIO DE\nNOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON FUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong> Disponer al\nejecutivo la prohibici\u00f3n del otorgamiento de Certificados de domicilio,\npermisos de uso, ni ninguna certificaci\u00f3n similar a las personas que no\nacrediten suficientemente su dominio o posesi\u00f3n del inmueble donde pretendan\nobtener el suministro el\u00e9ctrico o cualquier otro servicio similar.-<\/p>\n\n\n\n<p><strong>Art\u00edculo\n2\u00b0. <\/strong>La acreditaci\u00f3n del dominio o la posesi\u00f3n establecida en el art. 1\nde la presente ordenanza deber\u00e1 ser mediante cualquiera de los siguientes\ndocumentos:&nbsp; <\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>T\u00edtulo de Propiedad del Inmueble.<\/li><li>Mensura a su nombre con aprobaci\u00f3n de la Direcci\u00f3n de\nCatastro en caso de ser poseedor originario.<\/li><li>Cesi\u00f3n de Derechos Posesorios con la correspondiente\nMensura de Posesi\u00f3n con aprobaci\u00f3n en la Direcci\u00f3n de Catastro.<\/li><li>Autorizaci\u00f3n expresa y por escrito del titular o\nposeedor del inmueble, quien deber\u00e1 presentar alguno de los documentos\nsolicitados en los&nbsp; inc. A, B o C del\npresente art\u00edculo.-<\/li><\/ol>\n\n\n\n<p><strong>Art\u00edculo\n3\u00b0. &#8211;<\/strong> De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sala de sesiones, 22 de mayo de\n2024.-<\/p>\n\n\n\n<p>Aprobado por\nseis (6) Concejales, en general y en particular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disponer al D.E.M. la prohibici\u00f3n del otorgamiento de Certificados de domicilio, permisos de uso, ni ninguna certificaci\u00f3n similar a las personas que no acrediten suficientemente su dominio o posesi\u00f3n del inmueble.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8767","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8767"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8767\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}