{"id":8754,"date":"2024-05-08T09:36:27","date_gmt":"2024-05-08T12:36:27","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=8754"},"modified":"2024-05-08T09:36:27","modified_gmt":"2024-05-08T12:36:27","slug":"ordenanza-no-1420","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2024\/05\/08\/ordenanza-no-1420\/","title":{"rendered":"Ordenanza N\u00ba 1420"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>VISTO:<\/strong>\nLa Ordenanza N\u00b0 315 que regula el servicio de remises y taxis en la ciudad de\nNogoy\u00e1.<\/p>\n\n\n\n<p><strong>CONSIDERANDO:<\/strong>\n<\/p>\n\n\n\n<p>Que por motivo de la pandemia por &nbsp;Covid 19 que inici\u00f3 en el a\u00f1o 2020, y las\nrestricciones a la circulaci\u00f3n aplicadas en aquel momento por las autoridades,\nse alteraron los horarios de prestaci\u00f3n del servicio de taxis y remises;<\/p>\n\n\n\n<p>Que la mencionada pandemia ha generado\nuna marcada reducci\u00f3n de la movilidad de pasajeros en horarios nocturnos,\nacrecentada por el aumento de servicios de delivery y de tr\u00e1mites tipo moto\nmandado; <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que los prestadores del servicio\nmanifiestan que, con las condiciones macroecon\u00f3micas actuales, les resulta\nimposible prestar el servicio las 24 horas del d\u00eda como lo establece la\nOrdenanza N\u00b0 315;<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que es necesario regularizar la\nsituaci\u00f3n, adecuando la actual normativa, para evitar posibles sanciones a los\nprestadores de servicio, ante la imposibilidad del cumplimiento de las mismas.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, as\u00ed mismo, es importante\nrealizar otras modificaciones e incorporaciones a la normativa existente por lo\nque, este Cuerpo entiende necesario el dictado de la presente.-<\/p>\n\n\n\n<p>Por ello;<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE DEL MUNICIPIO DE\nNOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON FUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong> Modif\u00edquese el\ninc. g) del art\u00edculo 3 de la Ordenanza N\u00b0 315 que reza <em>\u201c<\/em><em>Art\u00edculo 3\u00ba.- Para ser permisionario, el interesado debe cumplimentar\nlos siguientes requisitos: (\u2026) g- Compromiso escrito de prestar el servicio\ndurante las veinticuatro (24) horas de todos los d\u00edas del a\u00f1o\u201d, <\/em>que quedar\u00e1 redactado de la siguiente manera\n<em>\u201cArt\u00edculo 3\u00ba.- Para ser permisionario, el\ninteresado debe cumplimentar los siguientes requisitos: (\u2026) g- Contar, dentro\nde la flota de veh\u00edculos, con al menos 1 (uno) con el equipamiento adecuado\npara transportar a personas con discapacidad y\/o con movilidad reducida, que\nrequieran la carga de alg\u00fan elemento como muletas, sillas de ruedas, o\ncualquier otro que exceda de un equipaje convencional.\u201d<\/em><\/p>\n\n\n\n<p><strong>Art\u00edculo\n2\u00b0- <\/strong>Modif\u00edquese el inc. e) del art\u00edculo 5 de la Ordenanza N\u00b0 315 que\nreza <em>\u201c<a>Art\u00edculo\n5\u00b0-. Los veh\u00edculos a utilizar en el servicio deben reunir los siguientes\nrequisitos: (\u2026) e- Ser de propiedad del permisionario, inscripto en el registro\nNacional de la Propiedad Automotor, o tener derecho a su utilizaci\u00f3n para la\nprestaci\u00f3n de este servicio en virtud de un contrato otorgado por su\npropietario.\u201d<\/a><\/em>, que quedar\u00e1\nredactado de la siguiente manera <em>\u201c<\/em><em>Art\u00edculo 5\u00b0.-&nbsp;&nbsp; Los veh\u00edculos a utilizar en el servicio\ndeben reunir los siguientes requisitos: (\u2026) e- Ser de propiedad del\npermisionario, inscripto en el registro Nacional de la Propiedad Automotor, o\ntener derecho a su utilizaci\u00f3n para la prestaci\u00f3n de este servicio en virtud de\nun contrato otorgado por su propietario, siendo el permisionario, en car\u00e1cter\nde titular del servicio, el \u00fanico habilitado para tramitar el alta o baja de\nlos mismos ante el \u00e1rea correspondiente a tal efecto.\u201d<\/em> <\/p>\n\n\n\n<p><strong>Art\u00edculo\n3\u00b0-<\/strong> Modif\u00edquese el inc.\nb) del Articulo 12 de la Ordenanza N\u00b0 315, que reza <em>\u201cArt\u00edculo 12\u00b0.- En la prestaci\u00f3n del Servicio se deben cumplimentar y\nrespetar: (\u2026) <a>b- Deber\u00e1 ser prestado durante las\nveinticuatro (24) horas de todos los d\u00edas del a\u00f1o.\u201d<\/a><\/em>, que quedar\u00e1 redactado de la\nsiguiente manera <em>\u201cArt\u00edculo 12\u00b0. &#8211; En la\nprestaci\u00f3n del Servicio se deben cumplimentar y respetar: (\u2026) b- Deber\u00e1 ser\nprestado durante las veinticuatro (24) horas de todos los d\u00edas del a\u00f1o. En el\nhorario nocturno, comprendido desde las 00 y hasta las 06 hs, el servicio se\nprestar\u00e1 mediante un sistema de turnos, facult\u00e1ndose al Departamento Ejecutivo\npara establecer los mismos, debiendo garantizar la prestaci\u00f3n del servicio por\nal menos una de las empresas o particulares afectados.\u201d<\/em><\/p>\n\n\n\n<p><strong>Art\u00edculo\n4\u00b0-<\/strong> Incorp\u00f3rese el Art\u00edculo N\u00b0\n19 a la Ordenanza N\u00b0 315, que establece <em>\u201cArt\u00edculo\n19\u00b0.- Establ\u00e9zcase como tarifa m\u00ednima para el traslado de pasajeros la\nequivalente a un litro y medio de nafta Infinia de YPF o la de mayor octanaje\nque esta posea.\u201d<\/em>, y proc\u00e9dase al corrimiento correspondiente de los\nart\u00edculos siguientes.-<\/p>\n\n\n\n<p><strong>Art\u00edculo\n5\u00b0.-<\/strong> Incorp\u00f3rese el Art\u00edculo N\u00b0\n20 a la Ordenanza N\u00b0 315, que establece <em>\u201cArt\u00edculo\n20\u00b0.- Establ\u00e9zcase que, tanto remises como taxis, tengan libertad de parada en\ncualquier sitio de la ciudad de Nogoy\u00e1, derogando cualquier disposici\u00f3n en\ncontrario.\u201d<\/em> y proc\u00e9dase al corrimiento correspondiente de los art\u00edculos\nsiguientes.-<\/p>\n\n\n\n<p><strong>Art\u00edculo\n6\u00b0.-<\/strong> Proc\u00e9dase a la realizaci\u00f3n\ndel texto ordenado de la Ordenanza N\u00b0 315 con las modificaciones establecidas\nen la presente.-<\/p>\n\n\n\n<p><strong>Art\u00edculo\n7\u00b0 <\/strong>De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sala de sesiones, 08 de mayo de 2024.-<\/p>\n\n\n\n<p>Aprobado por\nunanimidad, en general y en particular.<strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modificaci\u00f3n Ordenanza N\u00ba315 que regula el Servicio de Remises y Taxis <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8754","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=8754"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/8754\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=8754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=8754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=8754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}