{"id":6956,"date":"2023-04-12T07:52:52","date_gmt":"2023-04-12T10:52:52","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=6956"},"modified":"2023-04-12T07:52:52","modified_gmt":"2023-04-12T10:52:52","slug":"ordenanza-no1369","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2023\/04\/12\/ordenanza-no1369\/","title":{"rendered":"Ordenanza N\u00ba1369:"},"content":{"rendered":"\n<p>                                                <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n<strong>Ordenanza N\u00ba1.369<\/strong><\/p>\n\n\n\n<p><strong>VISTO<\/strong>: La necesidad de un espacio adecuado y\nseguro para el emplazamiento de equipos, herramientas, repuestos y accesorios\npertenecientes al Corral\u00f3n Municipal de Nogoy\u00e1; y,<\/p>\n\n\n\n<p><strong>CONSIDERANDO<\/strong>: Que nuestro corral\u00f3n local cuenta con\ndiversos equipos y herramientas que son utilizados tanto en el interior del\ninmueble mencionado, como as\u00ed tambi\u00e9n en el exterior (espacio p\u00fablico),\ndebiendo ser bien utilizados y devueltos en tiempo y forma.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que nuestra obligaci\u00f3n de preservar\nel patrimonio municipal, trabajando en pos de la eficacia en la administraci\u00f3n\nde la cosa p\u00fablica.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que debemos avanzar en mejoras de la\norganizaci\u00f3n y coordinaci\u00f3n para la ejecuci\u00f3n de pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p><strong>Por ello<\/strong>:<\/p>\n\n\n\n<p style=\"text-align:center\">EL CONCEJO\nDELIBERANTE<\/p>\n\n\n\n<p style=\"text-align:center\">del MUNICIPIO de\nNOGOY\u00c1<\/p>\n\n\n\n<p style=\"text-align:center\">SANCIONA CON\nFUERZA DE<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00b0.-<\/strong> Ordenar al\nDepartamento Ejecutivo Municipal la creaci\u00f3n de un \u201cPa\u00f1ol Municipal\u201d.<\/p>\n\n\n\n<p><strong>Art\u00edculo 2\u00ba.-<\/strong> El denominado\n\u201cPa\u00f1ol Municipal\u201d ser\u00e1 el espacio f\u00edsico designado para el almacenamiento,\ncuidado y control de herramientas, accesorios y equipos necesarios para los\ntrabajos realizados por el personal de Obras y Servicios P\u00fablicos; se\ndesarrollar\u00e1 e instituir\u00e1 dentro de los l\u00edmites f\u00edsicos del Corral\u00f3n Municipal\nde la Ciudad de Nogoy\u00e1.<\/p>\n\n\n\n<p><strong>Art\u00edculo 3\u00b0.-<\/strong> El Departamento\nEjecutivo Municipal dotar\u00e1 de uno o m\u00e1s empleados municipal\/es denominado\/s\npa\u00f1olero\/s, que estar\u00e1\/n a cargo del espacio en cuanto al mantenimiento del\norden, administraci\u00f3n de bienes, limpieza y organizaci\u00f3n e inventario de las\nherramientas, accesorios y equipos existentes en el mismo.<\/p>\n\n\n\n<p><strong>Art\u00edculo 4\u00b0.-<\/strong> La\nadministraci\u00f3n del pa\u00f1ol se focaliza en la entrada, almacenamiento y salida de\nherramientas, equipos m\u00f3viles y accesorios, de manera met\u00f3dica y c\u00edclica.\nEntendiendo a:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Entrada-Devoluci\u00f3n\nde herramientas, acompa\u00f1ada de su correcta carga de datos. <\/li><li>Almacenamiento-Organizaci\u00f3n\nseg\u00fan tipo y modelo, verificaci\u00f3n de estado, notificaci\u00f3n inmediata de toda\nanomal\u00eda de funcionamiento y control de stock. <\/li><li>Salida-Facilitaci\u00f3n\nde informaci\u00f3n y entrega de equipos, volcando los datos que corresponden a\nestas acciones.<\/li><\/ul>\n\n\n\n<p><strong>Art\u00edculo 5\u00ba.-<\/strong> Se procurar\u00e1\nmantener en buen estado de conservaci\u00f3n las herramientas e insumos existentes,\ntodo de acuerdo con el inventario; realiz\u00e1ndose un inventario en forma mensual\nde todas las existencias que se encuentren en el pa\u00f1ol. Se debe mantener la\nseguridad e integridad del espacio y, en los casos que exceda las capacidades\nde la administraci\u00f3n y no sea posible cumplir, se har\u00e1n las denuncias a las\nautoridades correspondientes.<\/p>\n\n\n\n<p><strong>Art\u00edculo 6\u00ba.-<\/strong> Con respecto al\norden y aseo del lugar, se debe m\u00ednimamente cumplir con los siguientes puntos,\na saber:<\/p>\n\n\n\n<p>1) Inspeccionar\nel \u00e1rea para asegurarse que no hay un exceso de herramientas, accesorios o\nequipos, y, si los hubiera, retirarlos del pa\u00f1ol, envi\u00e1ndolo a un almac\u00e9n de\nexcluidos o al patio del corral\u00f3n.<\/p>\n\n\n\n<p>2) Reorganizar las\nestanter\u00edas de almacenamiento y el almacenamiento en toda el \u00e1rea.<\/p>\n\n\n\n<p>3) Seleccionar\nuna o m\u00e1s \u00e1reas para la concentraci\u00f3n de herramientas o elementos de mayor\ndemanda m\u00e1s pr\u00f3ximo al sector de atenci\u00f3n de p\u00fablico, aliviando el resto de las\n\u00e1reas y pasillos de obst\u00e1culos. <\/p>\n\n\n\n<p>4) Mantener el\nespacio en total estado de aseo y orden, sosteniendo la limpieza en pos de\nprocurar la higiene en el ambiente denominado pa\u00f1ol.<\/p>\n\n\n\n<p><strong>Art\u00edculo 7\u00ba.-<\/strong> Est\u00e1 prohibido\nel ingreso a tercero, salvo cuando se est\u00e9n realizando tareas u obras\nnecesarias para el mantenimiento pa\u00f1ol, y estas ameriten la utilizaci\u00f3n del\nmismo por personas ajenas a la administraci\u00f3n, o por inspecci\u00f3n de funcionario\nsuperior correspondiente a la Secretaria de Obras y Servicios P\u00fablicos Nogoy\u00e1.\nTampoco se podr\u00e1 utilizar el pa\u00f1ol con fines personales, ajenos a los intereses\nmunicipales, ni realizar tareas ajenas al giro que tiene dicho espacio, como,\npor ejemplo: Realizar reuniones, depositar de mercader\u00edas impropias o alojar\nmateriales ajenos a las necesidades de mantenimiento o aseo del pa\u00f1ol. <\/p>\n\n\n\n<p><strong>Art\u00edculo 8\u00ba.-<\/strong> De forma.-<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Nogoy\u00e1, Sala de Sesiones, 12 de abril de\n2.023.-<\/p>\n\n\n\n<p>Aprobado\npor unanimidad en general y particular<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Creaci\u00f3n de un pa\u00f1ol para el resguardo de herramientas.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-6956","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6956"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6956\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}