{"id":6619,"date":"2022-11-30T10:07:36","date_gmt":"2022-11-30T13:07:36","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=6619"},"modified":"2022-11-30T10:07:36","modified_gmt":"2022-11-30T13:07:36","slug":"ordenanza-no1360","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2022\/11\/30\/ordenanza-no1360\/","title":{"rendered":"Ordenanza N\u00ba1360"},"content":{"rendered":"\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n&nbsp;&nbsp;<strong>Ordenanza\nN\u00ba1.360<\/strong><\/p>\n\n\n\n<p><strong>VISTO<\/strong>: La Ordenanza\nde Presupuesto de Gastos y Recursos para el a\u00f1o 2022; y,<\/p>\n\n\n\n<p><strong>CONSIDERANDO<\/strong>: Que dicho Presupuesto fue calculado durante finales del a\u00f1o 2021\nen base a las estimaciones, proyecciones e informaci\u00f3n disponible en el\nmomento, las cuales luego se vieron afectadas en mayor medida por el creciente\naumento del \u00edndice general de precios.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que este proyecto tiene por objeto la ampliaci\u00f3n del\nPresupuesto del corriente ejercicio en raz\u00f3n de modificaciones por mayores\nrecursos proyectados que los estimados al momento de la presentaci\u00f3n del\nreferido proyecto, tales como Coparticipaci\u00f3n de Impuesto Nacionales y\nProvinciales; mayor recaudaci\u00f3n de Tasas, principalmente la TISHPYS, ANR del\nEstado Provincial, Adenda por mayor financiamiento CDI Villa Ghiano y de\nreasignaci\u00f3n de partidas sub ejecutadas entre otras.. <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que atento a lo manifestado por el DEM, estos mayores ser\u00e1n\nvolcados a financiar el mayor gasto de personal producto de los sucesivos aumentos\nsalariales otorgados a fin de paliar los efectos de la inflaci\u00f3n acumulada a lo\nlargo del a\u00f1o y del aumento de los costos de bienes y servicios esenciales para\nel funcionamiento de todas las \u00e1reas Municipales.<\/p>\n\n\n\n<p><strong>Por ello<\/strong>: <\/p>\n\n\n\n<p style=\"text-align:center\">EL CONCEJO DELIBERANTE<\/p>\n\n\n\n<p style=\"text-align:center\">DEL MUNICIPIO DE NOGOYA<\/p>\n\n\n\n<p style=\"text-align:center\">SANCIONA CON FUERZA DE<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong> Ampl\u00edese en la suma de Pesos\nDoscientos diecinueve millones doscientos treinta y cuatro mil ciento treinta y\nseis con 74\/100 ($219.234.136,74) el total de Recursos para el a\u00f1o 2022, en los\nrubros detallados en el Cuadro 1 que forma parte de la presente; y por tanto,\nest\u00edmese en la suma de Pesos Mil quinientos once millones once mil\ncuatrocientos cincuenta y siete con 17\/100 ($1.511.011.457,17) el total de\nRecursos del Presupuesto General para el a\u00f1o 2022.<\/p>\n\n\n\n<p><strong>Art\u00edculo 2\u00ba.-<\/strong> Ampl\u00edese en la suma de Pesos\nDoscientos diecinueve millones doscientos treinta y cuatro mil ciento treinta y\nseis con 74\/100 ($219.234.136,74) el Presupuesto General de Gastos del a\u00f1o 2022,\nde acuerdo al Cuadro II que forma parte de la presente, y por lo tanto, fijase\nen la suma de Pesos Mil quinientos once millones once mil cuatrocientos\ncincuenta y siete con 17\/100 ($1.511.011.457,17) el total del Presupuesto\nGeneral de Gastos de 2022.<\/p>\n\n\n\n<p><strong>Art\u00edculo 3\u00ba.-<\/strong> Comun\u00edquese, publ\u00edquese,\nreg\u00edstrese y arch\u00edvese.-<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Nogoy\u00e1, Sala de Sesiones, 30 de noviembre\nde 2.022.-<\/p>\n\n\n\n<p>Aprobado por unanimidad en\ngeneral y particular<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampl\u00eda el Presupuesto 2022.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-6619","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6619"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6619\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}