{"id":6501,"date":"2022-10-12T07:01:55","date_gmt":"2022-10-12T10:01:55","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=6501"},"modified":"2022-10-12T07:01:55","modified_gmt":"2022-10-12T10:01:55","slug":"ordenanza-no1354","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2022\/10\/12\/ordenanza-no1354\/","title":{"rendered":"Ordenanza N\u00ba1354"},"content":{"rendered":"\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\n&nbsp;&nbsp;<strong>Ordenanza\nN\u00ba1.354<\/strong><\/p>\n\n\n\n<p><strong>VISTO<\/strong>: El incremento de accidentes viales\nocurridos a motociclistas y personas transportadas en ciclomotores y moto\nveh\u00edculos; y,<\/p>\n\n\n\n<p style=\"text-align:left\"><strong>CONSIDERANDO<\/strong>: Que ocho de cada diez accidentes\nproducidos en nuestra ciudad son protagonizados por ciclomotores y moto\nveh\u00edculos con un significativo n\u00famero de personas lesionadas al a\u00f1o. <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que si bien se realizan los\ncontroles diariamente por parte de la polic\u00eda y el \u00e1rea de tr\u00e1nsito municipal,\naun no se ha logrado una conciencia en el ciudadano de que esas medidas son\npara su seguridad y no para su molestia.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que para aquellos que circulan en\nciclomotores o motos, el uso del casco es considerado \u201cvital\u201d por especialistas\ny organismos oficiales que trabajan en la seguridad vial. <\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que los cascos salvan vidas al\nevitar golpes y heridas en la cabeza, que potencialmente pueden ocasionar\ngraves consecuencias.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que los motociclistas que no\nutilizan esta protecci\u00f3n tienen m\u00e1s riesgo de muerte o de sufrir lesiones\npermanentes.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que seg\u00fan la Ordenanza N\u00ba1072 es\nobligatorio el uso del casco protector en conductores y acompa\u00f1antes de moto\nveh\u00edculos.<\/p>\n\n\n\n<p><strong>Por ello<\/strong>: <\/p>\n\n\n\n<p style=\"text-align:center\">EL CONCEJO\nDELIBERANTE<\/p>\n\n\n\n<p style=\"text-align:center\">DEL MUNICIPIO DE\nNOGOYA<\/p>\n\n\n\n<p style=\"text-align:center\">SANCIONA CON\nFUERZA DE<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong> Ordenar al\nDepartamento Ejecutivo Municipal que, a trav\u00e9s de la Direcci\u00f3n de Tr\u00e1nsito,\nrealice campa\u00f1as de educaci\u00f3n, prevenci\u00f3n y difusi\u00f3n respecto de la importancia\ndel uso del casco.<\/p>\n\n\n\n<p><strong>Art\u00edculo 2\u00ba.-<\/strong> Establ\u00e9cese en\nel \u00e1mbito de la Municipalidad de Nogoy\u00e1 la exhibici\u00f3n en vidrieras de locales\ncomerciales, edificios p\u00fablicos municipales y espacios p\u00fablicos de nuestra\nciudad (plazas, parques y paseos) de forma sencilla y visible la importancia\ndel uso del casco en ciclomotores y moto veh\u00edculos.<\/p>\n\n\n\n<p><strong>Art\u00edculo 3\u00ba<\/strong>.- Entregar en las\nescuelas secundarias de nuestra ciudad, folletos informativos a los alumnos de\n5to y 6to a\u00f1o a fin de concientizar de la importancia del uso del casco.<\/p>\n\n\n\n<p><strong>Art\u00edculo 4\u00ba.-<\/strong> Solicitar al\nDepartamento Ejecutivo Municipal, que entable comunicaci\u00f3n con el Observatorio\nVial de la Provincia de Entre R\u00edos a fin de que puedan ocuparse de las\ncapacitaciones en diferentes lugares e instituciones de nuestra ciudad.<\/p>\n\n\n\n<p><strong>Art\u00edculo 5\u00ba.-<\/strong> De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Nogoy\u00e1, Sala de Sesiones, 12 de octubre de\n2.022.-<\/p>\n\n\n\n<p>Aprobado\npor unanimidad en general y particular<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Establece la realizaci\u00f3n de campa\u00f1as de uso del casco.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-6501","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6501"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/6501\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}