{"id":5263,"date":"2021-08-11T17:00:12","date_gmt":"2021-08-11T20:00:12","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=5263"},"modified":"2021-08-11T17:00:12","modified_gmt":"2021-08-11T20:00:12","slug":"ordenanza-no1303","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2021\/08\/11\/ordenanza-no1303\/","title":{"rendered":"Ordenanza N\u00ba1303"},"content":{"rendered":"<p><strong>Ordenanza N\u00ba1.303<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>VISTO<\/strong>: Nota del IAPV de fecha 05\/02\/2021 respecto al Grupo Habitacional 20 Viviendas; y,<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>CONSIDERANDO: <\/strong>Que por la misma se solicita a este Cuerpo Deliberativo que se autorice al Departamento Ejecutivo Municipal a aceptar la restituci\u00f3n por distracto parcial de donaci\u00f3n a un inmueble a favor del Municipio con destino a calle, del inmueble desglosado de la Matricula N\u00ba114.848 que se identifica con Plano N\u00ba35.952, Lote A, Partida Provincial N\u00ba122.158, localizada en la ciudad de Nogoy\u00e1, en la manzana N\u00ba412, con domicilio parcelario en calle 16 de Julio: vert. 12-esq.=42,30m-superficie: 244.25m2.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que corresponde hacer lugar a lo solicitado y dictar la presenta normativa.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p><strong>Por ello:<\/strong><\/p>\n<p>EL CONCEJO DELIBERANTE<\/p>\n<p>DEL MUNICIPIO DE NOGOYA<\/p>\n<p>SANCIONA CON FUERZA DE<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDENANZA<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Art\u00edculo 1\u00ba.-<\/u><\/strong> Autor\u00edcese al Departamento Ejecutivo Municipal a que, mediante Decreto, proceda a aceptar la restituci\u00f3n por distracto parcial de donaci\u00f3n a un inmueble a favor del Municipio con destino a calle, del inmueble desglosado de la Matricula N\u00ba114.848 que se identifica con Plano N\u00ba35.952, Lote A, Partida Provincial N\u00ba122.158, localizada en la ciudad de Nogoy\u00e1, en la Manzana N\u00ba412, con domicilio parcelario en calle 16 de Julio: vert. 12-esq.=42,30m-superficie: 244.25m2, conforme lo solicitado por el IAPV.<\/p>\n<p><strong><u>Art\u00edculo 2\u00ba.-<\/u><\/strong> Notif\u00edquese oportunamente y rem\u00edtase copia de la presente Ordenanza a la Escriban\u00eda Mayor del Gobierno de Entre R\u00edos.<\/p>\n<p><strong><u>Art\u00edculo 3\u00ba.-<\/u><\/strong> De forma.-<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0Nogoy\u00e1, Sala de Sesiones, 11 de agosto de 2.021.-<\/p>\n<p>\u00a0<\/p>\n<p>Aprobado por unanimidad en general y particular<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acepta restituci\u00f3n de un inmueble con destino a calle.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-5263","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/5263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5263"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/5263\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}