{"id":4609,"date":"2021-03-31T15:01:59","date_gmt":"2021-03-31T18:01:59","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=4609"},"modified":"2021-03-31T15:01:59","modified_gmt":"2021-03-31T18:01:59","slug":"ordenanza-no1286","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2021\/03\/31\/ordenanza-no1286\/","title":{"rendered":"Ordenanza N\u00ba1286"},"content":{"rendered":"<p><strong>Ordenanza N\u00ba1.286<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>VISTO<\/strong>: La preocupaci\u00f3n de la sociedad en cuanto a los consumos problem\u00e1ticos dentro de la ciudad de Nogoy\u00e1; y,<\/p>\n<p>\u00a0<\/p>\n<p><strong>CONSIDERANDO<\/strong>: Que por consumos problem\u00e1ticos se entiende a todos los consumos que afectan negativamente, en forma ocasional o sostenida en el tiempo, la salud f\u00edsica, ps\u00edquica del sujeto, y\/o las relaciones sociales pudiendo llegar a afectar el v\u00ednculo con la ley.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que los consumos problem\u00e1ticos pueden manifestarse como episodios ocasionales, abusos o adicciones a sustancias como el alcohol, el tabaco, drogas psicotr\u00f3picas legales o ilegales o producidos por ciertas conductas compulsivas de los sujetos hacia el juego, las tecnolog\u00edas digitales, la alimentaci\u00f3n, las compras o cualquier otro consumo percibido como incontrolable.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que la tem\u00e1tica de consumos problem\u00e1ticos est\u00e1 instalada en la sociedad desde hace muchos a\u00f1os, pero se ha sido profundizando \u00faltimamente, enraiz\u00e1ndose en todas las edades, lo que conlleva a grandes problemas sociales.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que el Departamento Ejecutivo Municipal ha demostrado su inter\u00e9s y preocupaci\u00f3n en el tema, lo que se traslada a la voluntad de este Cuerpo Deliberativo, quienes, tras concretarse reuniones conjuntas con distintos funcionarios municipales y provinciales, hemos decidido ocuparnos, procediendo al dictado de la presente Ordenanza en miras de trabajar en la prevenci\u00f3n de los consumos problem\u00e1ticos en el \u00e1mbito de la ciudad de Nogoy\u00e1.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Por ello<\/strong>:<\/p>\n<p>EL CONCEJO DELIBERANTE<\/p>\n<p>DEL MUNICIPIO DE NOGOYA<\/p>\n<p>SANCIONA CON FUERZA DE<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDENANZA<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Art\u00edculo 1\u00ba.-<\/u><\/strong> Decl\u00e1ranse de Inter\u00e9s Municipal todas las actividades municipales que se organicen y desarrollen en el a\u00f1o 2021 relacionadas con los \u201cConsumos Problem\u00e1ticos\u201d.<\/p>\n<p><strong><u>Art\u00edculo 2\u00ba.-<\/u><\/strong> El Departamento Ejecutivo Municipal deber\u00e1 crear un sello distintivo de esta actividad para ser utilizado en cada convocatoria de actividades municipales recreativas, deportivas o culturales que se realicen en el a\u00f1o 2021.<\/p>\n<p><strong><u>Articulo 3\u00ba.-<\/u><\/strong> Autor\u00edzase al Departamento Ejecutivo a adherir a la Municipalidad de Nogoy\u00e1 a la Red Provincial de Problem\u00e1ticas de Consumo.<\/p>\n<p><strong><u>Art\u00edculo 4\u00ba.-<\/u><\/strong> Autorizase al D. Ejecutivo a crear un equipo interdisciplinario en el \u00e1mbito de la Municipalidad de Nogoy\u00e1, integrado por funcionarios y distintos profesionales vinculados con la tem\u00e1tica, los cuales se encargar\u00e1n de fijar los lineamientos de trabajo y las actividades a desarrollar.<\/p>\n<p><strong><u>Art\u00edculo 5\u00ba.-<\/u><\/strong> Cr\u00e9ase el Padr\u00f3n de Colaboradores, donde podr\u00e1n inscribirse aquellos profesionales que de manera desinteresada y ad-honorem quieran colaborar con el equipo interdisciplinario, aportando sus conocimientos y disponiendo de su trabajo.<\/p>\n<p><strong><u>Art\u00edculo 6\u00ba.-<\/u><\/strong> Comun\u00edquese, publ\u00edquese, reg\u00edstrese y arch\u00edvese.-<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Nogoy\u00e1, Sala de Sesiones, 31 de marzo de 2.021.-<\/p>\n<p>\u00a0<\/p>\n<p>Aprobado por unanimidad en general y particular<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declaran de Inter\u00e9s Municipal las actividades municipales relacionadas con \u201cConsumos Problem\u00e1ticos\u201d.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-4609","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/4609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4609"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/4609\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}