{"id":3447,"date":"2020-11-26T15:00:34","date_gmt":"2020-11-26T18:00:34","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=3447"},"modified":"2020-11-26T15:00:34","modified_gmt":"2020-11-26T18:00:34","slug":"ordenanza-no1279","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2020\/11\/26\/ordenanza-no1279\/","title":{"rendered":"Ordenanza N\u00ba1279"},"content":{"rendered":"<p><strong>Ordenanza N\u00ba1279<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>VISTO<\/strong>: El pedido de algunos vecinos que proponen designar de nombre a una calle p\u00fablica de nuestra ciudad; y,<\/p>\n<p>\u00a0<\/p>\n<p><strong>CONSIDERANDO<\/strong>: Que habi\u00e9ndose realizado la apertura de dicha calle p\u00fablica, los vecinos proponen el nombre: Ex combatiente Rub\u00e9n Dar\u00edo Facciano.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que Rub\u00e9n Dar\u00edo Facciano cumpli\u00f3 servicios en la Conscripci\u00f3n en la Armada Argentina en el a\u00f1o 1981 y prest\u00f3 juramento a la Bandera Nacional el 20 de Junio de 1981, en Rio Grande, Tierra del Fuego. Al mismo tiempo se enteraba que deber\u00eda defender a la Patria y que ser\u00eda enviado a una guerra inminente. Su batall\u00f3n fue uno de los primeros en llegar, ya que su ubicaci\u00f3n era aproximada al lugar del conflicto.<\/p>\n<p>Perteneci\u00f3 al Batall\u00f3n de Infanter\u00eda N\u00ba5, particip\u00f3 en las Operaciones de Guerra del Atl\u00e1ntico Sur en resguardo de la soberan\u00eda Argentina de las Islas Malvinas, Georgia y S\u00e1ndwich del Sur y por ello el 2 de abril de 1983 recibi\u00f3 un Diploma de Honor y Bot\u00f3n Solapa en reconocimiento de los servicios prestados a la Patria. En lo personal form\u00f3 una familia con Nilda Godoy con la que tuvo cuatro hijos.<\/p>\n<p>Sus amigos y allegados lo describen como un hombre calmo, de hablar pausado, amable y siempre con una mirada con un dejo de tristeza.<\/p>\n<p>As\u00ed podemos describir a Rub\u00e9n Facciano, ciudadano nogoyaense que sirvi\u00f3 a su patria y vivi\u00f3 con muy poco reconocimiento.<\/p>\n<p>Su \u00faltimo domicilio fue el Barrio 130 Viviendas \u201cIslas Malvinas\u201d de Villa 3 de Febrero.<\/p>\n<p>Falleci\u00f3 el 11 de enero del 2013 producto de una larga enfermedad.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Por ello<\/strong>:<\/p>\n<p>EL CONCEJO DELIBERANTE<\/p>\n<p>DE LA CIUDAD DE NOGOY\u00c1<\/p>\n<p>SANCIONA CON FUERZA DE<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDENANZA<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Art\u00edculo 1\u00ba.-<\/u><\/strong> Des\u00edgnese con el nombre de \u201cEx combatiente Rub\u00e9n Dar\u00edo Facciano\u201d a la calle p\u00fablica perpendicular a Avda. Hip\u00f3lito Yrigoyen entre las calles Gobernador Le\u00f3n Sola y Virginia Quinodoz.<\/p>\n<p><strong><u>Art\u00edculo 2\u00ba.-<\/u><\/strong> Col\u00f3quese la se\u00f1aletica correspondiente.<\/p>\n<p><strong><u>Art\u00edculo 3\u00ba.-<\/u><\/strong> De forma.-<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nogoy\u00e1, Sala de Sesiones, 26 de noviembre de 2.020.-<\/p>\n<p>\u00a0<\/p>\n<p>Aprobado por unanimidad en general y particular<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asigna el nombre de \u201cRub\u00e9n Facciano\u201d a una calle.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3447","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3447"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3447\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}