{"id":3444,"date":"2020-11-18T15:00:25","date_gmt":"2020-11-18T18:00:25","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=3444"},"modified":"2020-11-18T15:00:25","modified_gmt":"2020-11-18T18:00:25","slug":"ordenanza-no1276","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2020\/11\/18\/ordenanza-no1276\/","title":{"rendered":"Ordenanza N\u00ba1276"},"content":{"rendered":"<p><a href=\"\/wp-content\/uploads\/2020\/12\/O-1276-ANEXO.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">0-1276-ANEXO.PDF<\/a><\/p>\n<p><strong>Ordenanza N\u00ba1276<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>EL CONCEJO DELIBERANTE<\/p>\n<p>DEL MUNICIPIO DE NOGOYA<\/p>\n<p>SANCIONA CON FUERZA DE<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDENANZA<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong><u>Art\u00edculo 1\u00ba.-<\/u><\/strong> Estimase en la suma de Pesos: setecientos ochenta y siete millones doscientos cincuenta y seis mil doscientos($787.256.200,00) el total de Recursos para el a\u00f1o 2021, destinado a atender erogaciones a que se refiere el art\u00edculo 2\u00ba, detallado en el Cuadro I que forma parte de la presente.<\/p>\n<p><strong><u>Art\u00edculo 2\u00ba.-<\/u><\/strong> Fijase en la suma de Pesos: setecientos ochenta y siete millones doscientos cincuenta y seis mil doscientos ($787.256.200,00) el total del Presupuesto general de Gastos de 2021, de acuerdo al Cuadro II que forma parte de la presente.<\/p>\n<p><strong><u>Art\u00edculo 3\u00ba.-<\/u><\/strong> Fijase en trescientos treinta y tres (333), el total de cargos de la Planta Permanente y en doscientos (200) los contratos transitorios.<\/p>\n<p><strong><u>Art\u00edculo 4\u00ba.-<\/u><\/strong> Autorizase a la Contadur\u00eda Municipal a realizar las imputaciones, modificaciones y ajustes que fueran necesarios para adecuar las registraciones presupuestarias a los Cuadros I y II que forman parte integrante de la presente.<\/p>\n<p><strong><u>Art\u00edculo 5\u00ba.-<\/u><\/strong> Estimase el C\u00e1lculo de Recursos 2021 para la Caja Municipal de Jubilaciones y Pensiones de Nogoy\u00e1 que ha sido fijado en Pesos: setecientos sesenta y nueve millones setecientos ochenta y un mil doscientos ($769.781.200,00).<\/p>\n<p><strong><u>Art\u00edculo 6\u00ba.-<\/u><\/strong> Fijase el total de Gastos del a\u00f1o 2021 para la Caja Municipal de Jubilaciones y Pensiones de Nogoy\u00e1 que ha sido fijado en Pesos: setecientos sesenta y nueve millones setecientos ochenta y un mil doscientos ($769.781.200,00).<\/p>\n<p><strong><u>Art\u00edculo 7\u00ba.-<\/u><\/strong> Fijase en Cuatro (4) el total de cargos de la planta permanente del Personal de la Caja Municipal de Jubilaciones y Pensiones de Nogoy\u00e1.<\/p>\n<p><strong><u>Art\u00edculo 8\u00ba.-<\/u><\/strong> Comun\u00edquese, publ\u00edquese, reg\u00edstrese y arch\u00edvese.-<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nogoy\u00e1, Sala de Sesiones, 18 de noviembre de 2.020.-<\/p>\n<p>\u00a0<\/p>\n<p>Aprobado por unanimidad en general y particular<\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprueba el Presupuesto para el a\u00f1o 2.021.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3444","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3444"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3444\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}