{"id":3367,"date":"2020-07-22T10:00:49","date_gmt":"2020-07-22T13:00:49","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=2831"},"modified":"2020-07-22T10:00:49","modified_gmt":"2020-07-22T13:00:49","slug":"ordenanza-no1263","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2020\/07\/22\/ordenanza-no1263\/","title":{"rendered":"Ordenanza N\u00ba1263"},"content":{"rendered":"<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/p>\n<p><strong>Ordenanza N\u00ba1263<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>VISTO<\/strong>: La Ordenanza Municipal N\u00ba209, promulgada en fecha 18\/06\/91; y,<\/p>\n<p>\u00a0<\/p>\n<p><strong>CONSIDERANDO<\/strong>: Que por Ordenanza N\u00ba209 se exim\u00eda de Tasa por extensi\u00f3n y visado de Carnet de Conducir al personal afectado a la conducci\u00f3n de veh\u00edculos que presten servicios en la Municipalidad de Nogoy\u00e1, Jefatura Departamental de Polic\u00eda y Asociaci\u00f3n de Bomberos Voluntarios Nogoy\u00e1.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que esta eximici\u00f3n es de suma importancia, ya que es un beneficio que la Municipalidad de Nogoy\u00e1 brinda a aquel personal que conduce veh\u00edculos, desarrollando una labor trascendental dentro de la sociedad, sea para cuidarnos la salud, como as\u00ed tambi\u00e9n para brindarnos seguridad y auxilio en situaciones complejas.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que desde el a\u00f1o 2014 la Municipalidad de Nogoy\u00e1 emite la Licencia Nacional de Conducir, por lo que la citada Ordenanza, si bien se sigui\u00f3 aplicando en lo cotidiano, qued\u00f3 obsoleta.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Que entendemos necesario derogar la Ordenanza N\u00ba209 para poder generar la presente, actualizando su contenido, adapt\u00e1ndola, de esta manera, al r\u00e9gimen vigente de emisi\u00f3n de la Licencia Nacional de Conducir.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Por ello<\/strong>:<\/p>\n<p>EL CONCEJO DELIBERANTE<\/p>\n<p>DEL MUNICIPIO DE NOGOYA<\/p>\n<p>SANCIONA CON FUERZA DE<\/p>\n<p>\u00a0<\/p>\n<p><strong>ORDENANZA<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong><u>Art\u00edculo 1\u00ba.-<\/u><\/strong> Der\u00f3guese la Ordenanza N\u00ba209, promulgada en fecha 18\/06\/91.<\/p>\n<p><strong><u>Art\u00edculo 2\u00ba.-<\/u><\/strong> Ex\u00edmase del Sellado Municipal por Extensi\u00f3n de Licencia Nacional de Conducir y Sellado Municipal por Certificado de Libre Deuda al personal afectado a la conducci\u00f3n (chofer) de veh\u00edculos que prestan servicios como tal, en la Municipalidad de Nogoy\u00e1, Jefatura Departamental de Polic\u00eda, Asociaci\u00f3n Bomberos Voluntarios de Nogoy\u00e1 y efectores de Salud P\u00fablica.<\/p>\n<p><strong><u>Art\u00edculo 3\u00ba.-<\/u><\/strong> Proh\u00edbase de acogerse al beneficio establecido en el art\u00edculo precedente a todo personal que no est\u00e9 afectado a la conducci\u00f3n de veh\u00edculos.<\/p>\n<p><strong><u>Art\u00edculo 4\u00ba.-<\/u><\/strong> Establ\u00e9zcase que para acogerse al beneficio establecido por el art\u00edculo 1\u00ba deber\u00e1 peticionarse por Mesa de Entradas, mediante nota simple del interesado, en la que se dejar\u00e1 expresamente asentado que es personal afectado a la conducci\u00f3n de veh\u00edculos y deber\u00e1 ser acompa\u00f1ada por una certificaci\u00f3n de su superior inmediato que acredite lo manifestado.<\/p>\n<p><strong><u>Art\u00edculo 5\u00ba.-<\/u><\/strong> La autorizaci\u00f3n para la eximici\u00f3n ser\u00e1 otorgada por el Secretario de Gobierno, Desarrollo Social y Relaciones Institucionales.<\/p>\n<p><strong><u>Art\u00edculo 6\u00ba.-<\/u><\/strong> Comun\u00edquese, reg\u00edstrese, publ\u00edquese y arch\u00edvese.-<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Nogoy\u00e1, Sala de Sesiones, 22 julio de 2.020.-<\/p>\n<p>\u00a0<\/p>\n<p>Aprobado por unanimidad en general y particular \u2013 sobre tablas<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>\u00a0<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exime del pago de los sellados para obtenci\u00f3n de la<br \/>\nLicencia de Conducir a choferes oficiales.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3367","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3367"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3367\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}