{"id":3324,"date":"2012-12-07T00:00:00","date_gmt":"2012-12-07T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no978\/"},"modified":"2012-12-07T00:00:00","modified_gmt":"2012-12-07T03:00:00","slug":"ordenanza-no978","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2012\/12\/07\/ordenanza-no978\/","title":{"rendered":"Ordenanza N\u00ba978"},"content":{"rendered":"<p>Crea el Programa de Estacionamiento Medido<\/p>\n<p><!--[if gte mso 9]><xml>\n<w_WordDocument>\n<w_View>Normal<\/w_View>\n<w_Zoom>0<\/w_Zoom>\n<w_TrackMoves \/>\n<w_TrackFormatting \/>\n<w_HyphenationZone>21<\/w_HyphenationZone>\n<w_PunctuationKerning \/>\n<w_ValidateAgainstSchemas \/>\n<w_SaveIfXMLInvalid>false<\/w_SaveIfXMLInvalid>\n<w_IgnoreMixedContent>false<\/w_IgnoreMixedContent>\n<w_AlwaysShowPlaceholderText>false<\/w_AlwaysShowPlaceholderText>\n<w_DoNotPromoteQF \/>\n<w_LidThemeOther>ES<\/w_LidThemeOther>\n<w_LidThemeAsian>X-NONE<\/w_LidThemeAsian>\n<w_LidThemeComplexScript>X-NONE<\/w_LidThemeComplexScript>\n<w_Compatibility>\n<w_BreakWrappedTables \/>\n<w_SnapToGridInCell \/>\n<w_WrapTextWithPunct \/>\n<w_UseAsianBreakRules \/>\n<w_DontGrowAutofit \/>\n<w_SplitPgBreakAndParaMark \/>\n<w_DontVertAlignCellWithSp \/>\n<w_DontBreakConstrainedForcedTables \/>\n<w_DontVertAlignInTxbx \/>\n<w_Word11KerningPairs \/>\n<w_CachedColBalance \/>\n<\/w_Compatibility>\n<w_BrowserLevel>MicrosoftInternetExplorer4<\/w_BrowserLevel>\n<m_mathPr>\n<m_mathFont m_val=\"Cambria Math\" \/>\n<m_brkBin m_val=\"before\" \/>\n<m_brkBinSub m_val=\"&#45;-\" \/>\n<m_smallFrac m_val=\"off\" \/>\n<m_dispDef \/>\n<m_lMargin m_val=\"0\" \/>\n<m_rMargin m_val=\"0\" \/>\n<m_defJc m_val=\"centerGroup\" \/>\n<m_wrapIndent m_val=\"1440\" \/>\n<m_intLim m_val=\"subSup\" \/>\n<m_naryLim m_val=\"undOvr\" \/>\n<\/m_mathPr><\/w_WordDocument>\n<\/xml><![endif]--><\/p>\n<p><!--[if gte mso 9]><xml>\n<w_LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"true\"\nDefSemiHidden=\"true\" DefQFormat=\"false\" DefPriority=\"99\"\nLatentStyleCount=\"267\">\n<w_LsdException Locked=\"false\" Priority=\"0\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Normal\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"heading 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 7\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 8\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 9\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 7\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 8\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 9\" \/>\n<w_LsdException Locked=\"false\" Priority=\"35\" QFormat=\"true\" Name=\"caption\" \/>\n<w_LsdException Locked=\"false\" Priority=\"10\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Title\" \/>\n<w_LsdException Locked=\"false\" Priority=\"1\" Name=\"Default Paragraph Font\" \/>\n<w_LsdException Locked=\"false\" Priority=\"11\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtitle\" \/>\n<w_LsdException Locked=\"false\" Priority=\"22\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Strong\" \/>\n<w_LsdException Locked=\"false\" Priority=\"20\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"59\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Table Grid\" \/>\n<w_LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Placeholder Text\" \/>\n<w_LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"No Spacing\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Revision\" \/>\n<w_LsdException Locked=\"false\" Priority=\"34\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"List Paragraph\" \/>\n<w_LsdException Locked=\"false\" Priority=\"29\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Quote\" \/>\n<w_LsdException Locked=\"false\" Priority=\"30\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Quote\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"19\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"21\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"31\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Reference\" \/>\n<w_LsdException Locked=\"false\" Priority=\"32\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Reference\" \/>\n<w_LsdException Locked=\"false\" Priority=\"33\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Book Title\" \/>\n<w_LsdException Locked=\"false\" Priority=\"37\" Name=\"Bibliography\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" QFormat=\"true\" Name=\"TOC Heading\" \/>\n<\/w_LatentStyles>\n<\/xml><![endif]--><!--[if gte mso 10]>\n\n\n<style>\n\/* Style Definitions *\/\ntable.MsoNormalTable\n{mso-style-name:\"Tabla normal\";\nmso-tstyle-rowband-size:0;\nmso-tstyle-colband-size:0;\nmso-style-noshow:yes;\nmso-style-priority:99;\nmso-style-qformat:yes;\nmso-style-parent:\"\";\nmso-padding-alt:0cm 5.4pt 0cm 5.4pt;\nmso-para-margin:0cm;\nmso-para-margin-bottom:.0001pt;\nmso-pagination:widow-orphan;\nfont-size:11.0pt;\nfont-family:\"Calibri\",\"sans-serif\";\nmso-ascii-font-family:Calibri;\nmso-ascii-theme-font:minor-latin;\nmso-fareast-font-family:\"Times New Roman\";\nmso-fareast-theme-font:minor-fareast;\nmso-hansi-font-family:Calibri;\nmso-hansi-theme-font:minor-latin;\nmso-bidi-font-family:\"Times New Roman\";\nmso-bidi-theme-font:minor-bidi;}\n<\/style>\n\n\n<![endif]--><\/p>\n<p class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/b><b style=\"mso-bidi-font-weight:\nnormal\"><span style=\"font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span>Ordenanza N&ordm;978<\/span><\/b><\/p>\n<p class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">EL HONORABLE CONCEJO DELIBERANTE<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">DE LA MUNICIPALIDAD DE NOGOYA<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">SANCIONA CON FUERZA DE<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-size:12.0pt;font-family:\n&quot;Times New Roman&quot;,&quot;serif&quot;\">ORDENANZA<\/span><\/b><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 1&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Crease el Programa de estacionamiento medido en el &aacute;mbito de la ciudad de Nogoy&aacute;, con el fin de procurar un orden y mejoramiento en el estacionamiento en la zona c&eacute;ntrica de la ciudad, el cual se regir&aacute; por las disposiciones establecidas en la presente. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 2&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Disponer el sistema de estacionamiento limitado con implementaci&oacute;n de tarjeta-reloj en el &aacute;mbito de la ciudad de Nogoy&aacute;, efectu&aacute;ndose el contralor de la referida modalidad mediante la utilizaci&oacute;n de tarjetas especialmente confeccionadas al efecto y en merito a las disposiciones de la presente. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 3&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Se considerara radio de estacionamiento limitado con sistema de control mediante tarjeta-reloj, el comprendido entre las calles: <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Al Norte: calle Boulevard Espa&ntilde;a, margen sur. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Al Sur: calle Quiroga y Taboada. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Al Este: calle 25 de Mayo. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Al Oeste: calle 9 de Julio.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Quedan tambi&eacute;n comprendidas dentro del radio de estacionamiento limitado las cuadras de calle 25 de Mayo, San Mart&iacute;n y 9 de Julio, entre calle Quiroga y Taboada y Gobernador Carlos Cont&iacute;n; las calles Caseros, Centenario, Alem, Urquiza, Tucum&aacute;n y Maip&uacute;, entre calles 9 de Julio y Moreno.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 4&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> El costo del estacionamiento medido en el per&iacute;metro establecido en el art&iacute;culo anterior, as&iacute; como el acarreo y estad&iacute;a de los veh&iacute;culos en infracci&oacute;n, ser&aacute;n los que establezca la Ordenanza Impositiva Anual. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 5&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> El Departamento Ejecutivo Municipal determinar&aacute; cu&aacute;l ser&aacute; el &oacute;rgano o &aacute;rea encargada de la comercializaci&oacute;n de las tarjetas de estacionamiento medido, debiendo realizar y registrar ingresos y egresos que deriven de la implementaci&oacute;n del presente sistema. Asimismo determinar&aacute; la forma y condiciones en que se proceder&aacute; a la venta de las tarjetas reloj al p&uacute;blico, quedando facultado a celebrar convenios con entidades sin fines de lucro, instituciones Educativas, comercios y el Centro Comercial de Nogoy&aacute;, pudiendo prever el Departamento Ejecutivo, costos diferenciales a favor de las mismas, para que las entidades y comercios puedan lograr un beneficio econ&oacute;mico a su favor, pero debiendo respetar &eacute;stas &uacute;ltimas el costo de venta para los usuarios fijado por la Ordenanza Impositiva Anual.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 6&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> El estacionamiento limitado con tarjeta reloj queda instituido en los siguientes d&iacute;as y horarios: <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">I- Entre los meses de octubre a abril inclusive: <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">De lunes a viernes de 8,00 horas a 12,30 y de 16:30 a 20,30 horas. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">D&iacute;as s&aacute;bados de 8,00 a 13,00 horas. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">II- Entre los meses de mayo a septiembre inclusive:<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">De lunes a viernes de 8:30 horas a 13:00 y de 16:00 a 20,00 horas.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">D&iacute;as s&aacute;bados de 9,00 a 13,00 horas.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">D&iacute;as s&aacute;bados despu&eacute;s de las 13,00 horas, domingos y feriados estacionamiento libre. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 7&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> La utilizaci&oacute;n de la tarjeta-reloj para el control de estacionamiento medido en el per&iacute;metro establecido, se realizar&aacute; de acuerdo a la reglamentaci&oacute;n que al efecto establezca el Departamento Ejecutivo Municipal, debiendo colocarse las tarjetas-reloj en el veh&iacute;culo de modo tal que resulten visibles desde el exterior. Cada tarjeta reloj podr&aacute; ser utilizada solo una vez y autorizar&aacute; el estacionamiento por el tiempo fijado en la misma, el cual no podr&aacute; exceder de una hora. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 8&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> En las zonas destinadas al estacionamiento limitado con tarjeta reloj, deber&aacute;n observarse todas las disposiciones existentes en cuanto a ordenamiento urbano y de tr&aacute;nsito, manteni&eacute;ndose la vigencia de la prohibici&oacute;n de estacionamiento a la izquierda, salvo que se encontrare debidamente autorizada otra forma de utilizaci&oacute;n. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 9&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Los propietarios o conductores de los automotores estacionados en cumplimiento del presente sistema asumen todo el riesgo al que est&aacute;n sometidos por su uso, ya sea por robo, da&ntilde;o total o parcial, incendio, destrucci&oacute;n, explosi&oacute;n, tumulto o cualquier perjuicio que pudiere producirse sobre los veh&iacute;culos y\/o personas y\/o animales que se encontraren en su interior, por la acci&oacute;n de personas y\/o cosas y\/u objetos guardados en &eacute;l, siendo el presente detalle meramente enunciativo, deslindando a la Municipalidad de Nogoy&aacute; de toda responsabilidad derivada de hechos o actos de cualquier &iacute;ndole que los produjeren, independientemente del origen de los mismos. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 10&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Todos los fondos ingresados, en concepto de venta de tarjetas-reloj y previa deducci&oacute;n de los gastos de impresi&oacute;n, ser&aacute;n afectados a: <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">l.- El 40 % al Presupuesto de Obras P&uacute;blicas con destino exclusivo para la construcci&oacute;n del Centro Municipal de Rehabilitaci&oacute;n creado por Ordenanza n&deg; 937. Una vez concretada la Obra, a la partida presupuestaria asignada para la manutenci&oacute;n y mejoras del Centro de Rehabilitaci&oacute;n.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">2.- El 40% al Presupuesto o partida presupuestaria de la Direcci&oacute;n de Tr&aacute;nsito, para educaci&oacute;n vial, adquisici&oacute;n de equipamiento, capacitaci&oacute;n, y mejoras del &aacute;rea. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">3.- El 20 % se depositar&aacute; en la cuenta extrapresupuestaria existente para satisfacer programas de salud, planes de prevenci&oacute;n, atenci&oacute;n, y tratamiento de enfermedades, que est&eacute;n contemplados en Ordenanzas Municipales o que a criterio del Departamento Ejecutivo, a trav&eacute;s del &aacute;rea de Desarrollo Social, sean necesarias contemplar. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 11&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Los controles del cumplimiento de la posesi&oacute;n de las tarjetas en los veh&iacute;culos que estacionen en el Radio de Estacionamiento medido ser&aacute;n efectuados por personal de Tr&aacute;nsito y Transporte, en el ejercicio y dentro del marco que sus funciones le conceden. El usuario deber&aacute; colocar claramente en la tarjeta la fecha y hora de inicio del tiempo de estacionamiento. Vencido el tiempo de la tarjeta el usuario tendr&aacute; diez minutos de tolerancia antes de labrarse el acta de infracci&oacute;n.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 12&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Ser&aacute;n consideradas infracciones al r&eacute;gimen establecido por la presente Ordenanza, las siguientes:<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">a) Falta de colocaci&oacute;n de tarjetas de estacionamiento.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">b) Permanecer estacionado fuera del per&iacute;odo de tiempo establecido en la tarjeta.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">c) Reutilizaci&oacute;n de la tarjeta de estacionamiento.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">d) Falsear el tiempo de permanencia en el espacio utilizado o utilizar una tarjeta sin su debida demarcaci&oacute;n.-<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Las infracciones enunciadas precedentemente, ser&aacute;n sancionadas con multas que se fijar&aacute;n entre el 20% y el 100% del salario b&aacute;sico municipal. La graduaci&oacute;n de la multa estar&aacute; determinada por la reincidencia del infractor.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">La sanci&oacute;n de multa podr&aacute; abonarse con una reducci&oacute;n del 50%, cuando exista reconocimiento voluntario para el pago de la infracci&oacute;n y no se hubiera dictado sentencia.-<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 13&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Exceptuase del estacionamiento medido y pago a los propietarios o locatarios de inmuebles destinados a vivienda familiar ubicados dentro del &aacute;rea de implementaci&oacute;n del sistema y que no posean garaje; los vecinos alcanzados por el presente art&iacute;culo deber&aacute;n requerir a la Municipalidad la tarjeta de libre estacionamiento, la cual tendr&aacute; un costo diferencial aplicado por la Ordenanza Impositiva Anual, debiendo acreditar a tal efecto los siguientes requisitos:<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">a) T&iacute;tulo de propiedad o contrato de locaci&oacute;n sellado, y vigente, con relaci&oacute;n al inmueble afectado;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">b) Domicilio en dicho inmueble acreditado con documento nacional de identidad;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">c) Propiedad del veh&iacute;culo a trav&eacute;s de fotocopia del respectivo t&iacute;tulo;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">d) Libre deuda de tasas municipales del inmueble afectado;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">e) Plano de edificaci&oacute;n o construcci&oacute;n presentado y aprobado por el &aacute;rea correspondiente de la Municipalidad de Nogoy&aacute; del cual surja que no posea garaje el inmueble afectado.-<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Se otorgar&aacute; un solo permiso por inmueble, por el t&eacute;rmino de un a&ntilde;o, y para ser utilizado s&oacute;lo en la cuadra perteneciente al inmueble. Tambi&eacute;n se otorgar&aacute; un solo permiso a los titulares de inmuebles sobre las cuales se encuentren edificados varios departamentos o sometidos al r&eacute;gimen de propiedad horizontal y no cuenten con garaje, siendo beneficiario el consorcio de copropietarios o el &uacute;nico titular del inmueble. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 14&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Los propietarios o locatarios de inmuebles destinados a vivienda familiar ubicados dentro del &aacute;rea de implementaci&oacute;n del sistema que posean garaje tendr&aacute;n estacionamiento libre y gratuito en ese espacio, debiendo identificar el dominio de los veh&iacute;culos a estacionar en el frente del mismo. Tambi&eacute;n tendr&aacute;n estacionamiento libre y gratuito en el espacio que el Departamento Ejecutivo establezca: los miembros de la Polic&iacute;a Departamental, del Sanatorio Urquiza S.R.L., de Establecimientos Educativos, de la Junta Departamental de Discapacidad, el Presidente Municipal y el cura p&aacute;rroco de la Bas&iacute;lica Nuestra Se&ntilde;ora del Carmen. El Departamento Ejecutivo podr&aacute; establecer una zona especial para comercios, correctamente demarcada dentro del &aacute;rea de estacionamiento medido, para la carga y descarga de mercader&iacute;as en los horarios establecidos por la legislaci&oacute;n local, estando exentos los usuarios o comerciantes del pago por el uso del estacionamiento.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 15&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Las empresas de remises y radio taxi y empresas o comercios que presten servicios de entrega a domicilio de sus productos (delivery), podr&aacute;n reservar un espacio para su uso exclusivo, el que ser&aacute; autorizado y determinado por el Departamento Ejecutivo. Correr&aacute;n por cuenta del beneficiario la provisi&oacute;n, instalaci&oacute;n y retiro de los carteles necesarios para la demarcaci&oacute;n del espacio, seg&uacute;n las indicaciones provistas por el Departamento Ejecutivo. Dichas empresas o comercios deber&aacute;n abonar una tarifa mensual especial, cuyo monto ser&aacute; determinado por la Ordenanza Impositiva Anual, en proporci&oacute;n a la cantidad de metros lineales autorizados a utilizar.-<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 16&deg;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Las personas con discapacidades motrices podr&aacute;n solicitar tambi&eacute;n el otorgamiento de una tarjeta de libre estacionamiento, que tendr&aacute; validez para ser utilizada en todo el radio de estacionamiento tarifado establecido en el art&iacute;culo tercero de la presente, debiendo adjuntar al Departamento Ejecutivo Municipal fotocopia del t&iacute;tulo del automotor, fotocopia del Documento Nacional de Identidad, y certificado de discapacidad.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 17&deg;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Las tarjetas reloj tarifadas contendr&aacute;n un color rojo o anaranjado. Las tarjetas especiales del art&iacute;culo 14&ordm; de la presente contendr&aacute;n un color verde; y las tarjetas especiales del art&iacute;culo 16&ordm; de la presente contendr&aacute;n un color azul. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 18.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Facultase al Poder Ejecutivo Municipal a realizar convenios con imprentas locales para la impresi&oacute;n de las tarjetas-reloj, las cuales deber&aacute;n contener el logo o insignia Municipal.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 19&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Facultase al Poder Ejecutivo Municipal a implementar la presente Ordenanza en un plazo no mayor a ciento veinte d&iacute;as corridos desde su promulgaci&oacute;n, debiendo efectuar una amplia y correcta informaci&oacute;n y publicidad por diferentes medios, sobre el sistema a implementar, la modalidad, costo, y dem&aacute;s informaci&oacute;n que permite a los usuarios conocer correctamente el alcance de la presente. Asimismo, fac&uacute;ltase al Poder Ejecutivo Municipal a comenzar con la implementaci&oacute;n del sistema de manera gradual por zonas ubicadas dentro del radio delimitado en el art&iacute;culo 3&ordm; de la presente. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 20&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Incorp&oacute;rese como inciso 10&ordm;) del Art&iacute;culo 43 del T&iacute;tulo V &ndash; SERVICIOS VARIOS &#8211; de la Ordenanza Impositiva N&ordm;953 el siguiente: &ldquo;Se abonar&aacute; por el uso del estacionamiento en la v&iacute;a p&uacute;blica por cada veh&iacute;culo la suma de $2 por el espacio de tiempo de una hora, y conforme lo dispuesto a la Ordenanza que establece el estacionamiento medido para veh&iacute;culos. Los propietarios o locatarios de inmuebles establecidos en el art&iacute;culo 13&ordm; abonar&aacute;n una suma mensual de pesos cien con una opci&oacute;n de pago bonificada para todo el a&ntilde;o calendario de $700.&rdquo;. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 21&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Derogase toda otra norma o disposici&oacute;n que se oponga a la presente. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 22&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Comun&iacute;quese, publ&iacute;quese, reg&iacute;strese y arch&iacute;vese.<\/span><\/p>\n<p align=\"right\" style=\"text-align:right\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p align=\"right\" style=\"text-align:right\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Nogoy&aacute;, Sala de Sesiones, 7 de diciembre de 2.012.-<\/span><\/p>\n<p align=\"right\" style=\"text-align:right\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Aprobado por mayor&iacute;a en general y particular<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crea el Programa de Estacionamiento Medido<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3324","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3324"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3324\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}