{"id":3292,"date":"2012-04-26T00:00:00","date_gmt":"2012-04-26T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no938\/"},"modified":"2012-04-26T00:00:00","modified_gmt":"2012-04-26T03:00:00","slug":"ordenanza-no938","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2012\/04\/26\/ordenanza-no938\/","title":{"rendered":"Ordenanza N\u00ba938"},"content":{"rendered":"<p>Aprueba Decreto N\u00ba010 que proh\u00edbe la venta de un veh\u00edculo destinado al \u00e1rea de discapacidad.<\/p>\n<p>&nbsp;<\/p>\n<div><b><span style=\"font-size: 11pt\">&nbsp;&nbsp;&nbsp;<\/span><\/b>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ordenanza N&ordm;938<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div style=\"text-align: justify\"><b>VISTO<\/b>: El Decreto N&ordm;010 del D. Ejecutivo Municipal de fecha 14\/12\/2.012; y<\/div>\n<div style=\"text-align: justify\">&nbsp;<\/div>\n<div style=\"text-align: justify\"><b>CONSIDERANDO:<\/b> Que el Sr. Presidente del Comit&eacute; Coordinador de Programas para Personas con Discapacidad solicita a este Municipio una constancia que el veh&iacute;culo objeto de dicho Decreto no podr&aacute; ser vendido, donado, transferido ni embargado por un per&iacute;odo de cuatro a&ntilde;os sin la previa autorizaci&oacute;n del &oacute;rgano de aplicaci&oacute;n de la Ley 19.279.<\/div>\n<div style=\"text-align: justify\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que con la finalidad de cumplimentar este requerimiento el Sr. Presidente Municipal ha dictado el Decreto de referencia y ha enviado el mismo para que este Concejo proceda a su ratificaci&oacute;n.<\/div>\n<div>&nbsp;<\/div>\n<div><b>Por ello:<\/b><\/div>\n<div>&nbsp;<\/div>\n<div align=\"center\">EL HONORABLE CONCEJO DELIBERANTE<\/div>\n<div align=\"center\">DE LA MUNICPALIDAD DE NOGOYA<\/div>\n<div align=\"center\">SANCIONA CON FUERZA DE<\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"center\"><b>ORDENANZA<\/b><\/div>\n<div>&nbsp;<\/div>\n<div style=\"text-align: justify\"><b><u>Art&iacute;culo 1&ordm;.-<\/u><\/b>&nbsp;Apru&eacute;base el Decreto N&ordm;010 del D. Ejecutivo.<\/div>\n<div style=\"text-align: justify\"><b><u>Art&iacute;culo 2&ordm;.-<\/u><\/b> Establ&eacute;cese que el veh&iacute;culo Dominio KRQ826, marca Renault modelo Master PH3 DCI 120 PKLUX deber&aacute; ser utilizado exclusivamente para el area de discapacidad y a los fines espec&iacute;ficos determinados por la Ley 19.279.<\/div>\n<div style=\"text-align: justify\"><b><u>Art&iacute;culo 3&ordm;.-<\/u><\/b> Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.-<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nogoy&aacute;, Sala de Sesiones, 26 de abril de 2.012.-<\/div>\n<div>&nbsp;<\/div>\n<div>Aprobado por unanimidad en general y particular<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aprueba Decreto N\u00ba010 que proh\u00edbe la venta de un veh\u00edculo destinado al \u00e1rea de discapacidad.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3292","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3292"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3292\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}