{"id":3290,"date":"2012-04-12T00:00:00","date_gmt":"2012-04-12T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no936\/"},"modified":"2012-04-12T00:00:00","modified_gmt":"2012-04-12T03:00:00","slug":"ordenanza-no936","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2012\/04\/12\/ordenanza-no936\/","title":{"rendered":"Ordenanza N\u00ba936"},"content":{"rendered":"<p>Declara de Inter\u00e9s Municipal la recuperaci\u00f3n funcional de un edificio municipal.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <b>Ordenanza N&ordm;936<\/b><\/p>\n<div>&nbsp;<\/div>\n<div><b>VISTO<\/b>: La necesidad de dotar a la Municipalidad de Nogoy&aacute; de un edificio apto para el funcionamiento adecuado de numerosas oficinas de sus departamentos Legislativo y Ejecutivo; y<\/div>\n<div>&nbsp;<\/div>\n<div><b>CONSIDERANDO:<\/b> que, entre las propiedades municipales se encuentra el inmueble sito en calle Belgrano N&ordm;868, de una superficie de 500,60 mts.2, sobre el que se levanta un antiguo edificio de enormes proporciones.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, la recuperaci&oacute;n de dicho edificio brindar&aacute; a la Municipalidad un lugar adecuado para que en su planta baja puedan funcionar todas las oficinas necesarias para el Honorable Concejo Deliberante (Sala de Sesiones, Secretar&iacute;a Administrativa, sede de los distintos bloques, sala de comisiones, ba&ntilde;os, cocina, biblioteca, etc.) y en su planta alta todas las oficinas que requiera el Departamento Ejecutivo.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, en la actualidad, debido a la carencia de lugares adecuados, la Municipalidad debe alquilar un inmueble sobre calle San Mart&iacute;n N&ordm;980, donde funciona el Juzgado de Faltas, y las distintas oficinas de la Coordinaci&oacute;n de Inspecci&oacute;n (&aacute;rea Tr&aacute;nsito, bromatolog&iacute;a, obras privadas, obras sanitarias, etc.) cuyo canon alcanza la suma de tres mil seiscientos pesos mensuales.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, la ubicaci&oacute;n actual de las oficinas del H. C. D. se encuentran en la planta alta y altos del edificio municipal, siendo de casi imposible acceso al mismo por sus empinadas y largas escaleras, tanto para los miembros y empleados que all&iacute; trabajan, como para los contribuyentes que quieran efectuar consultas y propuestas, o el p&uacute;blico y el periodismo que quiera concurrir a las sesiones, por la inadecuada distribuci&oacute;n de sus dependencias.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, la recuperaci&oacute;n funcional del edificio de calle Belgrano vendr&iacute;a as&iacute; a solucionar en forma integral y definitiva el problema edilicio de la Municipalidad de Nogoy&aacute;.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, el proyecto de refacci&oacute;n integral del edificio de calle Belgrano puede encargarse a la Maestra Mayor de Obras Sra. Cristina Amarillo, que reviste como personal de planta permanente, acordando las caracter&iacute;sticas de la obra encargada y remuneraci&oacute;n.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;Que, la Sra. Amarillo deber&aacute; efectuar un relevamiento del estado actual del inmueble, elaborar un proyecto t&eacute;cnico de refacciones en etapas y realizar un c&oacute;mputo m&eacute;trico o necesidades de material y mano de obra al efecto, que deber&aacute; ser sometido a consideraci&oacute;n y aprobaci&oacute;n de este HCD en el plazo de 60 d&iacute;as.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;Que, se facultar&aacute; a la Presidencia del Honorable Concejo Deliberante y a los presidentes de Bloques para que se encarguen de gestionar ante las autoridades nacionales y\/o provinciales que corresponda el financiamiento de la obra de refacci&oacute;n edilicia a realizar.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;Que, para encarar los distintos viajes y gestiones se habilitar&aacute; una cuenta presupuestaria suficiente cuya administraci&oacute;n estar&aacute; a cargo de la Vicepresidencia Municipal en su car&aacute;cter de Presidente nato del H. C. D.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;Que, de ser necesario, este H. C. D. podr&aacute; requerir la consulta t&eacute;cnica del Colegio de Profesionales de la Arquitectura e Ingenier&iacute;a de la ciudad de Nogoy&aacute;.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que, para el apoyo de la gesti&oacute;n financiera de la obra se requerir&aacute; la colaboraci&oacute;n de los legisladores departamentales y provinciales de Nogoy&aacute;.<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/div>\n<div><b>Por ello:<\/b><\/div>\n<div><b>&nbsp;<\/b><\/div>\n<div align=\"center\">EL HONORABLE CONCEJO DELIBERANTE<\/div>\n<div align=\"center\">DE LA MUNICIPALIDAD DE NOGOYA<\/div>\n<div align=\"center\">SANCIONA CON FUERZA DE<\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div align=\"center\"><b>ORDENANZA<\/b><\/div>\n<div>&nbsp;<\/div>\n<div><b><u>Art&iacute;culo 1&ordm;.-<\/u><\/b> Declarar de Inter&eacute;s Municipal la recuperaci&oacute;n funcional del edificio ubicado en el inmueble sito en calle Belgrano N&ordm;868 de una superficie de 500,60 mts.2,&nbsp;de propiedad de esta Municipalidad de Nogoy&aacute;.<\/div>\n<div><b><u>Art&iacute;culo 2&ordm;.-<\/u><\/b> Destinar el edificio recuperado en su planta baja para el funcionamiento de todas las oficinas necesarias del H. Concejo Deliberante y en su planta alta para las oficinas que sean requeridas por el Departamento Ejecutivo.<\/div>\n<div><b><u>Art&iacute;culo 3&ordm;.-<\/u><\/b> Encargar a la agente municipal Maestra Mayor de Obras Sra. Cristina Amarillo y\/o a quien la Secretar&iacute;a de Obras y Servicios P&uacute;blicos Municipal designe, para que efect&uacute;e las tareas profesionales y t&eacute;cnicas necesarias para elaborar un proyecto de refacci&oacute;n integral del edificio en sus plantas baja y alta por etapas y la confecci&oacute;n de un c&oacute;mputo m&eacute;trico de materiales y mano de obra que se requerir&aacute;, a fin de calcular los costos de la obra. Dicho proyecto deber&aacute; ser presentado en el plazo de 60 d&iacute;as para ser considerado y aprobado por el H. C. D.<\/div>\n<div><b><u>Art&iacute;culo 4&ordm;.-<\/u><\/b> Facultar al Presidente del H. C. D. y a los jefes de Bloques para llevar adelante todas las gestiones necesarias ante las autoridades nacionales y\/o provinciales para obtener un financiamiento de la obra. Podr&aacute;n requerir la colaboraci&oacute;n de los legisladores departamentales y provinciales de Nogoy&aacute;.<\/div>\n<div><b><u>Art&iacute;culo 5&ordm;.-<\/u><\/b> Habilitar una cuenta especial destinada a cubrir todos los gastos que la gesti&oacute;n requiera, cuya administraci&oacute;n estar&aacute; a cargo del Presidente del H. C. D.<\/div>\n<div><b><u>Art&iacute;culo 6&ordm;.-<\/u><\/b> Autorizar al Presidente del H. C. D. a requerir consultas t&eacute;cnicas al Colegio de Profesionales de la Arquitectura e Ingenier&iacute;a local, si fuera necesario.<\/div>\n<div><b><u>Art&iacute;culo 7&ordm;.-<\/u><\/b> Der&oacute;gase la Ordenanza N&ordm;243 y toda otra disposici&oacute;n que se contraponga con la presente.<\/div>\n<div><b><u>Art&iacute;culo 8&ordm;.-<\/u><\/b> Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.-<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;Nogoy&aacute;, Sala de Sesiones, 12 de abril de 2.012.-<\/div>\n<div>&nbsp;<\/div>\n<div>Aprobado por unanimidad en general, en particular aprobados por unanimidad &nbsp;los art&iacute;culos 1&ordm;, 3&ordm;, 5&ordm;, 7&ordm; y 8&ordm; y por mayor&iacute;a los art&iacute;culos 2&ordm;, 4&ordm; y 6&ordm;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Declara de Inter\u00e9s Municipal la recuperaci\u00f3n funcional de un edificio municipal.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3290"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3290\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}