{"id":3235,"date":"2009-12-21T00:00:00","date_gmt":"2009-12-21T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no859\/"},"modified":"2009-12-21T00:00:00","modified_gmt":"2009-12-21T03:00:00","slug":"ordenanza-no859","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2009\/12\/21\/ordenanza-no859\/","title":{"rendered":"Ordenanza N\u00ba859"},"content":{"rendered":"<p>Modifica el C\u00e1lculo de Recursos y Presupuesto de Gastos A\u00f1o 2009.<\/p>\n<p>&nbsp;<\/p>\n<div><b><font size=\"1\"><span style=\"font-size: 11pt; text-decoration: none; text-underline: none\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ordenanza N&ordm;859\/09<\/span><\/font><\/b><\/div>\n<div>&nbsp;<\/div>\n<div align=\"center\">EL HONORABLE CONCEJO DELIBERANTE<\/div>\n<div align=\"center\">DE LA MUNICIPALIDAD DE NOGOYA<\/div>\n<div align=\"center\">SANCIONA CON FUERZA DE<\/div>\n<div><b><font size=\"3\">&nbsp;<\/font><\/b><\/div>\n<div style=\"text-align: center\"><b><font size=\"3\">ORDENANZA<\/font><\/b><\/div>\n<div align=\"center\">&nbsp;<\/div>\n<div><b><u>Art&iacute;culo 1&ordm;.-<\/u><\/b> Modif&iacute;case la Ordenanza N&ordm;833, Decreto de Promulgaci&oacute;n N&ordm;743&nbsp;de fecha 27\/11\/2.008 autoriz&aacute;ndose al Departamento Ejecutivo a transferir la suma de Pesos Tres millones quinientos cuarenta y cuatro mil trescientos ochenta y ocho con sesenta y siete centavos&nbsp;($3.544.388,67.) de la Partidas Principales del Presupuesto General de Gastos para el a&ntilde;o 2009 &ldquo;Bienes de Capital&rdquo; pesos cientos veinte mil ($120.000-), &ldquo;Trabajos P&uacute;blicos&rdquo; pesos dos millones novecientos veinticuatro mil trescientos ochenta y ocho con sesenta y siete centavos ($2.924.388,67) y &ldquo;Bienes de Consumo y Servicios&rdquo; pesos quinientos mil ($500.000-), a las Partida &ldquo;Personal&rdquo;, pesos Un mill&oacute;n doscientos mil trescientos ($1.200.300,00), &ldquo;Intereses y Gastos de la Deuda&rdquo;, pesos ciento ochenta y ocho mil ochocientos ($188.800,00), &ldquo;Financiamiento&rdquo; Pesos Dos millones ciento cincuenta y cinco mil doscientos ochenta y ocho con sesenta y siete centavos ($2.155.288,67), de acuerdo a los cuadros Anexos&nbsp;que forman parte de la presente.<\/div>\n<div><b><u>Art&iacute;culo 2&ordm;.-<\/u><\/b> Modif&iacute;case la Ordenanza N&ordm;833, Decreto de Promulgaci&oacute;n N&ordm;743&nbsp;de fecha 27\/11\/2.008 autoriz&aacute;ndose al D. Ejecutivo a modificar el C&aacute;lculo de Recursos correspondiente al Ejercicio 2.009 de la siguiente forma: a) incrementando la Partida Principal &ldquo;Financiamiento&rdquo; en la suma de pesos un mill&oacute;n trescientos noventa y cinco mil cuatrocientos ochenta y ocho con sesenta y siete centavos&nbsp;($1.395.488,67); b) disminuyendo la Partida Principal &ldquo;Ingresos Corrientes&rdquo; por la suma de Pesos un mill&oacute;n trescientos noventa y cinco mil cuatrocientos ochenta y ocho con sesenta y siete centavos ($1.395.488,67), lo que se detallan en los Anexos que forman parte integrante de la presente.<\/div>\n<div><b><u>Art&iacute;culo 3&ordm; .<\/u><\/b>&#8211; Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.-&nbsp;&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div><span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nogoy&aacute;, Sala de Sesiones, 21 de diciembre de 2.009.-<\/span><\/div>\n<div>&nbsp;<\/div>\n<div>Aprobado por mayor&iacute;a en general y particular<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Modifica el C\u00e1lculo de Recursos y Presupuesto de Gastos A\u00f1o 2009.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3235","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3235"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3235\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}