{"id":3195,"date":"2014-11-27T00:00:00","date_gmt":"2014-11-27T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no1078\/"},"modified":"2014-11-27T00:00:00","modified_gmt":"2014-11-27T03:00:00","slug":"ordenanza-no1078","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2014\/11\/27\/ordenanza-no1078\/","title":{"rendered":"Ordenanza N\u00ba1078"},"content":{"rendered":"<p>Declara de Utilidad P\u00fablica la pavimentaci\u00f3n de calle Guillani.<\/p>\n<p><!--[if gte mso 9]><xml>\n<w_WordDocument>\n<w_View>Normal<\/w_View>\n<w_Zoom>0<\/w_Zoom>\n<w_TrackMoves \/>\n<w_TrackFormatting \/>\n<w_HyphenationZone>21<\/w_HyphenationZone>\n<w_PunctuationKerning \/>\n<w_ValidateAgainstSchemas \/>\n<w_SaveIfXMLInvalid>false<\/w_SaveIfXMLInvalid>\n<w_IgnoreMixedContent>false<\/w_IgnoreMixedContent>\n<w_AlwaysShowPlaceholderText>false<\/w_AlwaysShowPlaceholderText>\n<w_DoNotPromoteQF \/>\n<w_LidThemeOther>ES<\/w_LidThemeOther>\n<w_LidThemeAsian>X-NONE<\/w_LidThemeAsian>\n<w_LidThemeComplexScript>X-NONE<\/w_LidThemeComplexScript>\n<w_Compatibility>\n<w_BreakWrappedTables \/>\n<w_SnapToGridInCell \/>\n<w_WrapTextWithPunct \/>\n<w_UseAsianBreakRules \/>\n<w_DontGrowAutofit \/>\n<w_SplitPgBreakAndParaMark \/>\n<w_DontVertAlignCellWithSp \/>\n<w_DontBreakConstrainedForcedTables \/>\n<w_DontVertAlignInTxbx \/>\n<w_Word11KerningPairs \/>\n<w_CachedColBalance \/>\n<\/w_Compatibility>\n<w_BrowserLevel>MicrosoftInternetExplorer4<\/w_BrowserLevel>\n<m_mathPr>\n<m_mathFont m_val=\"Cambria Math\" \/>\n<m_brkBin m_val=\"before\" \/>\n<m_brkBinSub m_val=\"&#45;-\" \/>\n<m_smallFrac m_val=\"off\" \/>\n<m_dispDef \/>\n<m_lMargin m_val=\"0\" \/>\n<m_rMargin m_val=\"0\" \/>\n<m_defJc m_val=\"centerGroup\" \/>\n<m_wrapIndent m_val=\"1440\" \/>\n<m_intLim m_val=\"subSup\" \/>\n<m_naryLim m_val=\"undOvr\" \/>\n<\/m_mathPr><\/w_WordDocument>\n<\/xml><![endif]--><\/p>\n<p><!--[if gte mso 9]><xml>\n<w_LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"true\"\nDefSemiHidden=\"true\" DefQFormat=\"false\" DefPriority=\"99\"\nLatentStyleCount=\"267\">\n<w_LsdException Locked=\"false\" Priority=\"0\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Normal\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"heading 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 7\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 8\" \/>\n<w_LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 9\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 7\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 8\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 9\" \/>\n<w_LsdException Locked=\"false\" Priority=\"35\" QFormat=\"true\" Name=\"caption\" \/>\n<w_LsdException Locked=\"false\" Priority=\"10\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Title\" \/>\n<w_LsdException Locked=\"false\" Priority=\"1\" Name=\"Default Paragraph Font\" \/>\n<w_LsdException Locked=\"false\" Priority=\"11\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtitle\" \/>\n<w_LsdException Locked=\"false\" Priority=\"22\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Strong\" \/>\n<w_LsdException Locked=\"false\" Priority=\"20\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"59\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Table Grid\" \/>\n<w_LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Placeholder Text\" \/>\n<w_LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"No Spacing\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Revision\" \/>\n<w_LsdException Locked=\"false\" Priority=\"34\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"List Paragraph\" \/>\n<w_LsdException Locked=\"false\" Priority=\"29\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Quote\" \/>\n<w_LsdException Locked=\"false\" Priority=\"30\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Quote\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 1\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 2\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 3\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 4\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 5\" \/>\n<w_LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 6\" \/>\n<w_LsdException Locked=\"false\" Priority=\"19\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"21\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Emphasis\" \/>\n<w_LsdException Locked=\"false\" Priority=\"31\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Reference\" \/>\n<w_LsdException Locked=\"false\" Priority=\"32\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Reference\" \/>\n<w_LsdException Locked=\"false\" Priority=\"33\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Book Title\" \/>\n<w_LsdException Locked=\"false\" Priority=\"37\" Name=\"Bibliography\" \/>\n<w_LsdException Locked=\"false\" Priority=\"39\" QFormat=\"true\" Name=\"TOC Heading\" \/>\n<\/w_LatentStyles>\n<\/xml><![endif]--><!--[if gte mso 10]>\n\n\n<style>\n\/* Style Definitions *\/\ntable.MsoNormalTable\n{mso-style-name:\"Tabla normal\";\nmso-tstyle-rowband-size:0;\nmso-tstyle-colband-size:0;\nmso-style-noshow:yes;\nmso-style-priority:99;\nmso-style-qformat:yes;\nmso-style-parent:\"\";\nmso-padding-alt:0cm 5.4pt 0cm 5.4pt;\nmso-para-margin:0cm;\nmso-para-margin-bottom:.0001pt;\nmso-pagination:widow-orphan;\nfont-size:11.0pt;\nfont-family:\"Calibri\",\"sans-serif\";\nmso-ascii-font-family:Calibri;\nmso-ascii-theme-font:minor-latin;\nmso-fareast-font-family:\"Times New Roman\";\nmso-fareast-theme-font:minor-fareast;\nmso-hansi-font-family:Calibri;\nmso-hansi-theme-font:minor-latin;\nmso-bidi-font-family:\"Times New Roman\";\nmso-bidi-theme-font:minor-bidi;}\n<\/style>\n\n\n<![endif]--><\/p>\n<p class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Ordenanza N&ordm;1.078<\/span><\/b><\/p>\n<p class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/b><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">VISTO<\/span><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">: El Proyecto de obra denominado &ldquo;Pavimentaci&oacute;n de calle Seraf&iacute;n Guillani entre 9 de Julio y Moreno&rdquo;<\/span><span lang=\"ES-TRAD\" style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;;\nmso-ansi-language:ES-TRAD\">,<\/span><span style=\"font-size:12.0pt;font-family:\n&quot;Times New Roman&quot;,&quot;serif&quot;\"> y <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">CONSIDERANDO:<\/span><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Que con los vecinos de esta arteria de nuestra ciudad se han venido realizando distintas reuniones a fin de concretar la realizaci&oacute;n de la obra de pavimentaci&oacute;n a los fines de mejorar la transitabilidad y cerramiento consolidado de la trama vial de esta zona.<\/span><\/p>\n<p style=\"text-align:justify;text-indent:35.4pt\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Que los vecinos han manifestado no tener problemas en llevar a cabo la ejecuci&oacute;n de la obra mediante la modalidad de Contribuci&oacute;n por Mejoras.-<\/span><\/p>\n<p style=\"text-align:justify;text-indent:35.4pt\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Que la Secretaria de Obras y Servicios P&uacute;blicos ha realizado informe t&eacute;cnico de la obra a realizar y costo de los materiales a emplear.<\/span><\/p>\n<p style=\"text-align:justify;text-indent:35.4pt\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Que analizada la composici&oacute;n de los vecinos beneficiarios de la obra resultan en su mayor&iacute;a con capacidad contributiva, para poder afrontar los costos de la obra, que se realizar&iacute;a bajo administraci&oacute;n directa de la municipalidad con personal y maquinarias propios, realiz&aacute;ndose licitaci&oacute;n y compra del hormig&oacute;n necesario.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que de acuerdo a lo legislado en la Ley 10027, en el &ldquo;Cap&iacute;tulo IV De los Bienes y Rentas Municipales&rdquo;, en el Art.14&ordm; inc. g) establece como parte de los recursos municipales, las contribuciones por mejoras.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que de acuerdo a lo legislado en la Ley 10027 en el Art.108&ordm; inc.4 y sus modificatorias, es deber del Presidente Municipal hacer recaudar, mensualmente o en los per&iacute;odos que las ordenanzas establezcan las tasas, rentas y dem&aacute;s tributos que correspondan al Municipio e invertir la renta de acuerdo a las autorizaciones otorgadas.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que para el cobro de la contribuci&oacute;n por mejoras es necesario sancionar una Ordenanza Especial donde se fijen los valores de referencia y se establezcan las modalidades de pago seg&uacute;n lo legislado en el &uacute;ltimo p&aacute;rrafo del Art. 123&ordm; del C&oacute;digo Tributario Municipal en vigencia &ldquo;Sea cual fuere la forma de ejecuci&oacute;n de la obra realizada o a realizarse, la determinaci&oacute;n de los importes a cobrar y la modalidad de pago se establecer&aacute;n por Ordenanza especial que al efecto se deber&aacute; sancionar.&rdquo;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que est&aacute; en vigencia la Ordenanza 531, modificada por la Ordenanza N&ordm; 979 mediante la cual es posible instrumentar este tipo de obra mediante el sistema de ahorro previo a partir de convenio con grupos de vecinos, mediante aporte anticipado del valor de los materiales, o de los materiales necesarios para su implementaci&oacute;n.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que se ha presupuestado la misma considerando el valor de materiales y mano de obra y uso de equipamiento.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-tab-count:1\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Que corresponde adem&aacute;s declarar de utilidad p&uacute;blica la obra identificada con &ldquo;pavimentaci&oacute;n calle Seraf&iacute;n Guillani entre 9 de Julio y Moreno&rdquo;, poniendo a consideraci&oacute;n de los vecinos un registro de oposici&oacute;n. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Por ello:<\/span><\/b><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">EL HONORABLE CONCEJO DELIBERANTE<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">DE LA MUNICIPALIDAD DE NOGOYA<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">SANCIONA CON FUERZA<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p align=\"center\" style=\"text-align:center\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:normal\"><span style=\"font-size:12.0pt;font-family:\n&quot;Times New Roman&quot;,&quot;serif&quot;\">ORDENANZA<\/span><\/b><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 1&ordm;.-<\/span><\/u><\/b><b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> <\/span><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Declarase de Utilidad P&uacute;blica la obra &ldquo;Pavimentaci&oacute;n calle Seraf&iacute;n Guillani entre 9 de Julio y Moreno&rdquo;. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 2&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> La obra comprende, unos 126 metros lineales aproximados y un ancho de calzada promedio de 5,50 mts. se concretar&aacute;n unos 693 m&sup2; de pavimento r&iacute;gido de Hormig&oacute;n Tipo H21 con armado de hierro en malla Simma de 0,15 x 0,25 mts. x 4,2 mm de espesor sobre un paquete estructural de broza no menor a 0,20 metros incluyendo, tareas de proyecto, nivelaci&oacute;n, compactaci&oacute;n, colocado del material, tomado de juntas y otras obras menores que son relacionadas con m&aacute;quinas y personal municipal.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 3&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Decl&aacute;rese obligatorio para los propietarios, poseedores y\/o usufructuarios de inmuebles ubicados como frentistas de la calle detallada en el <span style=\"mso-bidi-font-weight:\nbold\">art&iacute;culo 1&ordm;<\/span>, el pago del costo que determine este Municipio de conformidad a lo dispuesto en la presente Ordenanza y al importe que resulte como valor total de la obra, que estar&aacute; conformado por los costos de obra, materiales, mano de obra y gastos generales de obra nueva, cuyo detalle y valores monetarios obran en Anexo I, que forma parte de la presente.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 4&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Fijase el valor de obra en $ 320.000 (Pesos trescientos veinte mil) el costo total de la obra y por tratarse de una extensi&oacute;n de aproximadamente ciento veintis&eacute;is metros, considerando ambas aceras, el costo por metro lineal de frente alcanza la suma de $ 1.270 (Pesos un mil doscientos setenta), que a sus efectos incluye costo de los materiales necesarios para la construcci&oacute;n de la obra prevista en articulo 2&ordm;, mano de obra, uso de maquinaria, equipo y gastos generales de obra. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 5&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> A los fines de la determinaci&oacute;n del costo total a abonar por propietario, poseedores y\/o usufructuarios afectados por la obra descripta en el a<span style=\"mso-bidi-font-weight:\nbold\">rt&iacute;culo 2&ordm;<\/span>, se multiplicar&aacute; el valor equivalente como precio fijado en el art&iacute;culo 4&ordm;, a valores vigentes al momento de la liquidaci&oacute;n, por los metros lineales de frente de cada propiedad de acuerdo a las planillas catastrales del municipio actualizadas a la fecha de extensi&oacute;n o libramiento de las notificaciones.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 6&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Los pagos de los vecinos originados para la obra mencionada en el a<span style=\"mso-bidi-font-weight:\nbold\">rt&iacute;culo 2&ordm;<\/span>, deber&aacute;n ingresarse a una cuenta especial del Recurso Contribuci&oacute;n por Mejoras, bajo la denominaci&oacute;n del n&uacute;mero de la presente Ordenanza una vez promulgada.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 7&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> El pago de los importes resultantes por contribuci&oacute;n por mejora que esta obra provoca, podr&aacute;n ser abonados de la siguiente manera:<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">a) Pago anticipado, bajo la modalidad prevista en el art 4&ordm; de la ordenanza N&ordm; 979, modificada por la 531, benefici&aacute;ndose con el descuento previsto en la misma norma.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">b) Al contado con un descuento del 20% (veinte por ciento) del valor total, considerando tal la que se abone dentro de los 30 d&iacute;as de finalizada la obra.-<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">c) En 6 cuotas iguales, mensuales y consecutivas sin inter&eacute;s.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">d) En 12, 24 o 36 cuotas iguales, mensuales y consecutivas con un inter&eacute;s del 15% (quince por ciento) anual sobre saldos, liquidado por sistema franc&eacute;s.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span lang=\"ES-TRAD\" style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;;mso-ansi-language:\nES-TRAD\">Art&iacute;culo 8&ordm;.-<\/span><\/u><\/b><span lang=\"ES-TRAD\" style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;;mso-ansi-language:ES-TRAD\"> Los frentistas que demuestren la imposibilidad del pago dentro de las alternativas previstas en el <span style=\"mso-bidi-font-weight:bold\">art&iacute;culo 7&ordm;<\/span>, provocada por una situaci&oacute;n permanente o transitoria, lo que surgir&aacute; de un estudio socio-econ&oacute;mico realizado por intermedio del Departamento Ejecutivo, podr&aacute;n acceder a un plan especial de hasta 60 (Sesenta) cuotas mensuales m&aacute;s el inter&eacute;s de financiaci&oacute;n de la presente. Al cesar la situaci&oacute;n que provoca la imposibilidad de pago, los interesados deber&aacute;n adecuar el pago del saldo en las condiciones previstas en los incisos c) o d) del a<span style=\"mso-bidi-font-weight:\nbold\">rt&iacute;culo 7&ordm;, con una tasa de inter&eacute;s reducida en un tercio de la que se ha fijado en el mismo.<\/span><\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 9&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Anualmente, en fecha establecida por el Departamento Ejecutivo, los frentistas beneficiados por planes especiales, seg&uacute;n el art&iacute;culo anterior, deber&aacute;n presentar una declaraci&oacute;n jurada de la cual surja su situaci&oacute;n socioecon&oacute;mica, por la que se evaluar&aacute; la continuidad del mismo. <\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 10&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> A los fines de la emisi&oacute;n de las respectivas notificaciones de deudas se tomar&aacute;n como base las planillas catastrales del municipio actualizadas a la fecha de extensi&oacute;n o libramiento, procedi&eacute;ndose a celebrar el respectivo convenio particular de pago entre el propietario afectado y la Municipalidad a los fines de su recupero; en el caso de que el propietario no recibiese las mismas no se los exime de las obligaciones pendientes siendo v&aacute;lida en este caso la publicaci&oacute;n period&iacute;stica de car&aacute;cter general.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 11&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Las cuotas de liquidaciones que no se abonen en t&eacute;rmino, incurrir&aacute;n autom&aacute;ticamente en mora sin que sea necesario la interpelaci&oacute;n previa ni requerimiento judicial, al simple vencimiento de las mismas y deber&aacute;n ser abonadas por el propietario o poseedor con m&aacute;s el inter&eacute;s resarcitorio previsto en la Ordenanza Impositiva vigente, para pagos fuera de t&eacute;rmino; fijase los d&iacute;as 15 de cada mes o el posterior h&aacute;bil si este no lo fuera como vencimiento de las cuotas por financiaci&oacute;n de la obra.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 12&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Las propiedades &ndash; frentistas &ndash; responden por el pago de esta deuda de car&aacute;cter fiscal, con el privilegio que establecen los c&oacute;digos y leyes vigentes, quedando afectada hasta su total cancelaci&oacute;n.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 13&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> A todos los efectos se deja expresamente establecido que la indicaci&oacute;n del nombre del propietario, poseedor o usufructuario que se consigne en la notificaci&oacute;n de deuda a expedirse es simplemente indicativo, respondiendo por la misma la propiedad afectada, cualquiera fuere su propietario real.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 14&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> En todos los casos de transferencia, subdivisi&oacute;n, modificaci&oacute;n de dominio o constituci&oacute;n de derechos reales, los Escribanos o profesionales actuantes deber&aacute;n solicitar conjuntamente con el libre deuda, se les informe si el inmueble est&aacute; afectado al pago por contribuci&oacute;n por mejoras de las obras descriptas en el a<span style=\"mso-bidi-font-weight:bold\">rt&iacute;culo 2<\/span>&ordm;, que se encuentren ejecutadas, en ejecuci&oacute;n o simplemente dispuestas, debiendo adem&aacute;s observar:<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">a) Que en las escrituras o instrumentos del acto deber&aacute; constar que se ha abonado la totalidad de la deuda vencida liquidada y certificada por la Municipalidad, por este concepto, con m&aacute;s intereses, gastos y honorarios si los hubiese, o en su defecto la aceptaci&oacute;n expresa de la misma por parte del adquirente, el cual ser&aacute; solidariamente responsable con el deudor anterior.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">b) Que s&oacute;lo podr&aacute; transmitirse el dominio de la propiedad afectada por obras de pavimentaci&oacute;n enunciadas en el <span style=\"mso-bidi-font-weight:bold\">art&iacute;culo 2&ordm;<\/span>, haci&eacute;ndose cargo el adquirente de las cuotas que venzan en adelante, de lo cual deber&aacute; dejarse constancia en los respectivos instrumentos.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">c) En los casos de subdivisi&oacute;n de propiedades, posterior a la adopci&oacute;n de planes de pago, los responsables deber&aacute;n cancelar el saldo de la deuda vencida a la fecha de su divisi&oacute;n, pudiendo solicitar la divisi&oacute;n de la deuda no vencida en forma proporcional a los metros lineales de frente de los lotes en que se divida la propiedad, pudiendo cancelar la misma al contado sin descuento o en un plan de pagos incluyendo intereses de financiaci&oacute;n previsto en el <span style=\"mso-bidi-font-weight:\nbold\">art&iacute;culo 7&ordm;<\/span>, inc. c), en cuotas mensuales cuyo plazo no podr&aacute; superar el de la deuda original.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 15&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;;mso-bidi-font-weight:\nbold\"> Cuando alguno de los frentistas afectados por la obra de pavimentaci&oacute;n establecida en el a<\/span><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">rt&iacute;culo 2&ordm;<span style=\"mso-bidi-font-weight:bold\"> no cuente con los servicios de cloacas o agua potable, la Municipalidad realizar&aacute; por cuenta del frentista las conexiones hasta pasar la l&iacute;nea determinada por el cord&oacute;n cuneta.<\/span><\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Articulo 16&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;;mso-bidi-font-weight:\nbold\"> El pago de los importes resultantes por los trabajos descriptos en el <\/span><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">art&iacute;culo15&ordm;<span style=\"mso-bidi-font-weight:bold\">, ser&aacute;n abonados por los propietarios, poseedores y\/o usufructuarios en las formas establecidas en el a<\/span>rt&iacute;culo 7&ordm;<span style=\"mso-bidi-font-weight:bold\"> de la presente Ordenanza. <\/span><\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 17&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;;mso-bidi-font-weight:\nbold\"> A efectos de determinar la oposici&oacute;n de los contribuyentes afectados al pago de contribuci&oacute;n por mejoras, referidas a esta obra, cr&eacute;ase el Registro de Oposici&oacute;n, para lo cual los frentistas que sean beneficiarios directos de la misma, que deseen oponerse a su realizaci&oacute;n, dispondr&aacute;n de un plazo de 10 d&iacute;as corridos, a partir de la publicaci&oacute;n de su apertura, para dejar constancia por escrito de dicha circunstancia, con su firma y aclaraci&oacute;n. En caso que los frentistas que se opongan superen en m&aacute;s de un 50% los metros lineales de frente, considerando ambas aceras, la municipalidad podr&aacute; desistir de la realizaci&oacute;n de la obra.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b><u><span style=\"font-size:\n12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 18&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Autorizase al D. E. a efectuar las modificaciones presupuestarias necesarias para el cumplimiento de la presente Ordenanza y a realizar las imputaciones cuyas erogaciones demanden las inversiones a realizar.<\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><b style=\"mso-bidi-font-weight:\nnormal\"><u><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Art&iacute;culo 19&ordm;.-<\/span><\/u><\/b><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"> Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.- <span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/span><\/span><\/p>\n<p style=\"text-align:justify\" class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;\nfont-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span><\/p>\n<p class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\"><span style=\"mso-spacerun:yes\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Nogoy&aacute;, Sala de Sesiones, 27 de noviembre de 2.014.-<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">&nbsp;<\/span><\/p>\n<p class=\"MsoNoSpacing\"><span style=\"font-size:12.0pt;font-family:&quot;Times New Roman&quot;,&quot;serif&quot;\">Aprobado por unanimidad en general y particular<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declara de Utilidad P\u00fablica la pavimentaci\u00f3n de calle Guillani.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3195","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3195"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/3195\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}