{"id":2973,"date":"2007-10-12T00:00:00","date_gmt":"2007-10-12T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no803\/"},"modified":"2007-10-12T00:00:00","modified_gmt":"2007-10-12T03:00:00","slug":"ordenanza-no803","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2007\/10\/12\/ordenanza-no803\/","title":{"rendered":"Ordenanza N\u00ba803"},"content":{"rendered":"<p>Adhesi\u00f3n al PLAN NACER, tendiente a la reducci\u00f3n de la mortalidad<br \/>\nmaterno infantil en la Provincia de Entre R\u00edos.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"\/userfiles\/file\/hcd\/hcd-nogoya.jpg\" \/><br \/>\n<meta http-equiv=\"Content-Type\" content=\"text\/html; charset=utf-8\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_filelist.xml\" rel=\"File-List\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_themedata.thmx\" rel=\"themeData\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_colorschememapping.xml\" rel=\"colorSchemeMapping\" \/><!--[if gte mso 9]><xml>\n \n  Normal\n  0\n  \n  \n  21\n  \n  \n  false\n  false\n  false\n  \n  ES\n  X-NONE\n  X-NONE\n  \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n  \n  MicrosoftInternetExplorer4\n  \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n  \n<\/xml><![endif]--><!--[if gte mso 9]><![endif]--><\/p>\n<style type=\"text\/css\">\n<!--\n \/* Font Definitions *\/\n @font-face\n\t{\"MS Mincho\";\n\tpanose-1:2 2 6 9 4 2 5 8 3 4;\n\tmso-font-alt:\"&#65325;&#65331; &#26126;&#26397;\";}\n@font-face\n\t{\"Cambria Math\";\n\tpanose-1:2 4 5 3 5 4 6 3 2 4;}\n@font-face\n\t{\"@MS Mincho\";\n\tpanose-1:2 2 6 9 4 2 5 8 3 4;}\n \/* Style Definitions *\/\n p.MsoNormal, li.MsoNormal, div.MsoNormal\n\t{\n\tmso-style-parent:\"\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";\n\tmso-fareast-\"Times New Roman\";}\nh1\n\t{\n\tmso-style-link:\"T\u00edtulo 1 Car\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\ttext-align:center;\n\tpage-break-after:avoid;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";}\nh4\n\t{\n\tmso-style-link:\"T\u00edtulo 4 Car\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\tpage-break-after:avoid;\n\tborder:none;\n\tpadding:0cm;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";}\nspan.Ttulo1Car\n\t{mso-style-name:\"T\u00edtulo 1 Car\";\n\tmso-style-link:\"T\u00edtulo 1\";\n\tfont-weight:bold;}\nspan.Ttulo4Car\n\t{mso-style-name:\"T\u00edtulo 4 Car\";\n\tmso-style-link:\"T\u00edtulo 4\";\n\tfont-weight:bold;}\n.MsoChpDefault\n\t{\n\tfont-size:10.0pt;}\n@page Section1\n\t{size:612.0pt 792.0pt;\n\tmargin:70.85pt 3.0cm 70.85pt 3.0cm;}\ndiv.Section1\n\t{page:Section1;}\n \/* List Definitions *\/\n @list l0\n\t{}\n@list l0:level1\n\t{mso-level-text:\"%1)\";\n\ttext-indent:-18.0pt;}\nol\n\t{margin-bottom:0cm;}\nul\n\t{margin-bottom:0cm;}\n--><\/style>\n<p><!--[if gte mso 10]>\n\n\n<style>\n \/* Style Definitions *\/\n table.MsoNormalTable\n\t{mso-style-name:\"Tabla normal\";\n\tmso-style-parent:\"\";\n\tfont-size:10.0pt;\"Times New Roman\",\"serif\";}\n<\/style>\n\n\n<![endif]--><\/p>\n<div align=\"center\"><b><span style=\"font-size: 11pt\">Ordenanza N&ordm;803<\/span><\/b><\/div>\n<div style=\"border-right: medium none; border-top: medium none; border-left: medium none; border-bottom: medium none; text-align: center\"><b><font size=\"3\"><span style=\"font-size: 11pt\">Dto. de Promulgaci&oacute;n N&ordm;556 &ndash; 12\/10\/2.007<\/span><\/font><\/b><\/div>\n<div align=\"center\"><b>&nbsp;<\/b><\/div>\n<div align=\"center\">EL HONORABLE CONCEJO DELIBERANTE<\/div>\n<p align=\"center\">DE LA MUNICIPALIDAD DE NOGOYA<\/p>\n<p align=\"center\">SANCIONA CON FUERZA DE<\/p>\n<div align=\"center\">&nbsp;<\/div>\n<div style=\"text-align: center\"><b style=\"font-size: 14px\">ORDENANZA<\/b><\/div>\n<div>&nbsp;<\/div>\n<p><b><u>Art&iacute;culo 1&ordm;.-<\/u><\/b> Adhi&eacute;rase la Municipalidad de Nogoy&aacute; a los objetivos generales propuestos por el PLAN NACER, tendiente a la reducci&oacute;n de la mortalidad materno infantil&nbsp;en nuestra Provincia, a posibilitar la accesibilidad y la cobertura formal de la poblaci&oacute;n en materia de salud y a la conformaci&oacute;n de nuevos esquemas de gesti&oacute;n, financiamiento y asignaci&oacute;n de recursos para tal fin.<\/p>\n<p><b><u>Art&iacute;culo 2&ordm;.-<\/u><\/b> Autor&iacute;zase al Departamento Ejecutivo Municipal a celebrar los Convenios de Gesti&oacute;n y Administraci&oacute;n que resulten necesarios con la Unidad de Gesti&oacute;n del Seguro Provincial (UGSP), los que regir&aacute;n la relaci&oacute;n entre la Municipalidad y la citada Unidad, adem&aacute;s de las disposiciones de esta Ordenanza, la normativa provincial, municipal, nacional&nbsp;e internacional que regule el desenvolvimiento del PLAN NACER, en lo referente a su implementaci&oacute;n en jurisdicci&oacute;n del Municipio de Nogoy&aacute;.<\/p>\n<p><b><u>Art&iacute;culo 3&ordm;.-<\/u><\/b> Autor&iacute;cese al Departamento Ejecutivo Municipal a delegar en el Coordinador de Promoci&oacute;n y Gesti&oacute;n Social de la Municipalidad de Nogoy&aacute; la facultad de celebrar y ratificar los Convenios de Administraci&oacute;n que sean necesarios realizar para la implementaci&oacute;n del PLAN NACER en la ciudad de Nogoy&aacute;.<\/p>\n<p><b><u>Art&iacute;culo 4&ordm;.-<\/u><\/b> Des&iacute;gnese en car&aacute;cter de Efectores, a los fines de implementar el PLAN NACER en jurisdicci&oacute;n del Municipio de Nogoy&aacute;, a las siguientes unidades ejecutoras: a) Dispensario Municipal Dr. Adalberto Griffoni, b) Dispensario Municipal Dr. Mello, c) Dispensario Municipal Dr. Ghiano-Hermana Mar&iacute;a Martina Moreira y d) Centro Integrador Comunitario (CIC) a los que se autoriza a suscribir Convenios de Gesti&oacute;n y Administraci&oacute;n que sean necesarios para implementar el PLAN NACER, en los t&eacute;rminos que determine el Departamento Ejecutivo Municipal.<\/p>\n<p><b><u>Art&iacute;culo 5&ordm;.-<\/u><\/b> Ac&eacute;ptese el financiamiento establecido por el PLAN NACER,&nbsp;tendiente a brindar cobertura m&eacute;dico asistencial dirigida a la poblaci&oacute;n elegible del SEGURO MATERNO INFANTIL PROVINCIAL (SMIP) que integren el padr&oacute;n de beneficiarios inscriptos, confeccionado a tal fin. Se considerar&aacute; poblaci&oacute;n elegible del SMIP a las mujeres embarazadas, pu&eacute;rperas hasta cuarenta y cinco (45) d&iacute;as posteriores a la finalizaci&oacute;n del embarazo, por cualquier causa, los ni&ntilde;os y ni&ntilde;as menores de seis (6) a&ntilde;os domiciliados en el territorio de nuestra Provincia sin cobertura expl&iacute;cita de salud y debidamente registrada en el Padr&oacute;n de Beneficiarios Inscriptos.<\/p>\n<p><b><u>Art&iacute;culo 6&ordm;.-<\/u><\/b> Autor&iacute;cese al Coordinador de Promoci&oacute;n y Gesti&oacute;n Social de la Municipalidad de Nogoy&aacute; a la apertura de una cuenta bancaria especial, destinada exclusiva y excluyentemente a recibir y administrar los fondos que sean girados como consecuencia del PLAN NACER en la ciudad de Nogoy&aacute; con destino a los Efectores que deba administrar en virtud de los Convenios de Administraci&oacute;n y Gesti&oacute;n a celebrar con la UGSP.<\/p>\n<p><b><u>Art&iacute;culo 7&ordm;.-<\/u><\/b> Autor&iacute;cese al Departamento Ejecutivo Municipal a realizar la apertura de cuentas bancarias especiales destinadas a los Efectores designados en el Art&iacute;culo 4&ordm;, que ser&aacute; utilizada exclusiva y excluyentemente a recibir y administrar los fondos que sean girados en el marco de la implementaci&oacute;n del PLAN NACER en la ciudad de Nogoy&aacute; como consecuencia de los Convenios de Administraci&oacute;n y Gesti&oacute;n a celebrar entre los efectores y la UGSP.<\/p>\n<p><b><u>Art&iacute;culo 8&ordm;.-<\/u><\/b> La ejecuci&oacute;n de los fondos transferidos por la UGSP deber&aacute; realizarse en base al Plan de Inversi&oacute;n que ser&aacute; elaborado por el equipo de salud, a trav&eacute;s del cual se establecer&aacute;n las prioridades acordes a las necesidades de salud del &aacute;rea sanitaria correspondiente.<\/p>\n<p><b><u>Art&iacute;culo 9&ordm;.-<\/u><\/b> Los fondos que la UGSP transfiera a los efectores en el marco del PLAN NACER, deber&aacute;n ser aplicados taxativamente a los fines que a continuaci&oacute;n se detallan:<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>1)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>Mejoras en la infraestructura del Efector<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>2)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>Capacitaci&oacute;n de los recursos humanos dependiente del Efector a fin de brindar una mejor prestaci&oacute;n del servicio a la poblaci&oacute;n, cuyos agentes deber&aacute;n transferir los conocimientos adquiridos hacia el interior de la instituci&oacute;n.<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>3)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>Contrataci&oacute;n de servicios externos a los efectos de mejorar la cantidad y calidad de atenci&oacute;n y gesti&oacute;n administrativa, en caso que el efector no contase con el recurso de referencia del mismo.<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>4)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>Compra y reparaci&oacute;n del equipamiento orientado a la mejora en la prestaci&oacute;n.<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>5)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>Fortalecimiento de la actividad de promoci&oacute;n y difusi&oacute;n sanitaria, tales como talleres, instancias de recreaci&oacute;n, jornadas, rondas sanitarias, traslados e informes para dichas actividades.<\/p>\n<p style=\"margin-left: 36pt; text-indent: -18pt; text-align: justify\"><span>6)<span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span><\/span>En la ejecuci&oacute;n de los fondos, adem&aacute;s de las directrices taxativas anteriores se dar&aacute; prioridad a las inversiones dirigidas a mejorar la calidad y cantidad de la atenci&oacute;n materno infantil.<\/p>\n<p><b><u>Art&iacute;culo 10&ordm;.-<\/u><\/b> En caso de incumplimiento de lo dispuesto en los art&iacute;culos anteriores, los efectores o sus administradores ser&aacute;n pasibles de las sanciones establecidas en los correspondientes Convenios de Gesti&oacute;n y\/o Administraci&oacute;n a suscribir en el marco del PLAN NACER y a las medidas disciplinarias y\/o civiles y\/o penales que correspondan.<\/p>\n<p><b><u>Art&iacute;culo 11&ordm;.-<\/u><\/b> Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.-<\/p>\n<div>&nbsp;<\/div>\n<p><span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Nogoy&aacute;, Sala de Sesiones, 8 de Octubre de 2007.-<\/p>\n<div>&nbsp;<\/div>\n<p><span style=\"font-size: 12pt\">Aprobado por unanimidad en general y particular &ndash; sobre tablas<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"texto\"><a href=\"\/userfiles\/file\/hcd\/2007\/O-0803.pdf\"><img decoding=\"async\" alt=\"\" border=\"0\" src=\"\/img\/pdf_icon.gif\" \/> Ordenanza N&ordm; 0803<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adhesi\u00f3n al PLAN NACER, tendiente a la reducci\u00f3n de la mortalidad<br \/>\nmaterno infantil en la Provincia de Entre R\u00edos.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-2973","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2973\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}