{"id":2916,"date":"2006-02-02T00:00:00","date_gmt":"2006-02-02T03:00:00","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/ordenanza-no743\/"},"modified":"2006-02-02T00:00:00","modified_gmt":"2006-02-02T03:00:00","slug":"ordenanza-no743","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2006\/02\/02\/ordenanza-no743\/","title":{"rendered":"Ordenanza N\u00ba743"},"content":{"rendered":"<p>Modifica Ord 502 ( Caja de Jubilaciones Municipal ). Directorio,<br \/>\nmandato, descuento jubilatorio, contribuci\u00f3n patronal.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"\/userfiles\/file\/hcd\/hcd-nogoya.jpg\" \/><br \/>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_filelist.xml\" rel=\"File-List\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_themedata.thmx\" rel=\"themeData\" \/>\n<link href=\"file:\/\/\/C:%5CDOCUME%7E1%5Cusuario%5CCONFIG%7E1%5CTemp%5Cmsohtmlclip1%5C01%5Cclip_colorschememapping.xml\" rel=\"colorSchemeMapping\" \/><!--[if gte mso 9]><xml>\n \n  Normal\n  0\n  \n  \n  21\n  \n  \n  false\n  false\n  false\n  \n  ES\n  X-NONE\n  X-NONE\n  \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n  \n  MicrosoftInternetExplorer4\n  \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n   \n  \n<\/xml><![endif]--><!--[if gte mso 9]><![endif]--><\/p>\n<style type=\"text\/css\">\n<!--\n \/* Font Definitions *\/\n @font-face\n\t{\"Cambria Math\";\n\tpanose-1:2 4 5 3 5 4 6 3 2 4;}\n \/* Style Definitions *\/\n p.MsoNormal, li.MsoNormal, div.MsoNormal\n\t{\n\tmso-style-parent:\"\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";\n\tmso-fareast-\"Times New Roman\";}\nh1\n\t{\n\tmso-style-link:\"T\u00edtulo 1 Car\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\ttext-align:center;\n\tpage-break-after:avoid;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";}\np.MsoBodyText, li.MsoBodyText, div.MsoBodyText\n\t{\n\tmso-style-link:\"Texto independiente Car\";\n\tmargin:0cm;\n\tmargin-bottom:.0001pt;\n\ttext-align:center;\n\tfont-size:12.0pt;\"Times New Roman\",\"serif\";\n\tmso-fareast-\"Times New Roman\";}\nspan.Ttulo1Car\n\t{mso-style-name:\"T\u00edtulo 1 Car\";\n\tmso-style-link:\"T\u00edtulo 1\";\n\tfont-weight:bold;}\nspan.TextoindependienteCar\n\t{mso-style-name:\"Texto independiente Car\";\n\tmso-style-link:\"Texto independiente\";}\n.MsoChpDefault\n\t{\n\tfont-size:10.0pt;}\n@page Section1\n\t{size:612.1pt 792.1pt;\n\tmargin:3.0cm 110.55pt 34.0pt 110.55pt;}\ndiv.Section1\n\t{page:Section1;}\n--><\/style>\n<p><!--[if gte mso 10]>\n\n\n<style>\n \/* Style Definitions *\/\n table.MsoNormalTable\n\t{mso-style-name:\"Tabla normal\";\n\tmso-style-parent:\"\";\n\tfont-size:10.0pt;\"Times New Roman\",\"serif\";}\n<\/style>\n\n\n<![endif]--><\/p>\n<div style=\"text-align: center\"><b><span style=\"font-size: 11pt\"><span id=\"1228303950135S\" style=\"display: none\">&nbsp;<\/span><\/span><\/b><b><span style=\"font-size: 11pt\">Ordenanza N&ordm;743<\/span><\/b><\/div>\n<p style=\"text-align: center\"><b><span style=\"font-size: 11pt\">Promulgaci&oacute;n autom&aacute;tica &ndash; Ley 3001 &ndash; art. 112&ordm; inc. 3)<\/span><\/b><\/p>\n<div style=\"text-align: center\">EL HONORABLE CONCEJO DELIBERANTE<\/div>\n<div style=\"text-align: center\">DE LA MUNICIPALIDAD DE&nbsp;NOGOYA<\/div>\n<div style=\"text-align: center\">SANCIONA CON FUERZA<\/div>\n<p>&nbsp;<\/p>\n<p><span id=\"1228303949793E\" style=\"display: none\">&nbsp;<\/span><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<p>\n<meta content=\"text\/html; charset=utf-8\" http-equiv=\"Content-Type\" \/><br \/>\n<meta content=\"Word.Document\" name=\"ProgId\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Generator\" \/><br \/>\n<meta content=\"Microsoft Word 12\" name=\"Originator\" \/><\/p>\n<div style=\"text-align: center\"><b style=\"font-size: 14px\">ORDENANZA<\/b><\/div>\n<div>&nbsp;<\/div>\n<p><b><u>Art&iacute;culo 1&ordm;.-<\/u><\/b> Modif&iacute;canse los Art&iacute;culos 3&ordm; y 5&ordm; y los inc. a y b del Art. 27&ordm; de la Ordenanza 502, Decreto de Promulgaci&oacute;n N&ordm;167 del a&ntilde;o 1.999, los que quedar&aacute;n redactados de la siguiente manera: &ldquo;<u>Art&iacute;culo 3&ordm;.-<\/u> La conducci&oacute;n de la Caja estar&aacute; a cargo de un Directorio compuesto por 1 (un) Presidente, 4 (cuatro) Vocales en representaci&oacute;n de los empleados activos y pasivos y 1 (un) Concejal por cada Bloque Legislativo que integren el Honorable Concejo Deliberante de la Ciudad de Nogoy&aacute; que desempe&ntilde;ar&aacute;n sus funciones ad-honorem, designados de la siguiente manera: a) El Presidente ser&aacute; designado por el Presidente de la Municipalidad, quien en el mismo acto designar&aacute; un suplente, no pudiendo ocupar ninguno de estos cargos el Presidente de la Municipalidad.<\/p>\n<p>b) Dos representantes de los empleados y obreros de la Municipalidad en actividad, e igual n&uacute;mero de suplentes.<\/p>\n<p>c) Dos representantes de los Jubilados y Pensionados beneficiarios de la Caja, e igual n&uacute;mero de suplentes.<\/p>\n<p>d) De los Vocales Titulares, activos y pasivos del Directorio, se elegir&aacute; uno a simple pluralidad de votos, que actuar&aacute; como Secretario.<\/p>\n<p>Los Vocales indicados en los incisos precedentes, para ser elegidos como integrantes del Directorio, deber&aacute;n tener una antig&uuml;edad como agentes de la Municipalidad de Nogoy&aacute; no inferior a 3 (tres) a&ntilde;os a la fecha de elecci&oacute;n. Decl&aacute;rese incompatible la participaci&oacute;n, como miembro del Directorio, de parientes en l&iacute;nea recta, en todos los grados y colaterales hasta el segundo grado, sea por consanguinidad o afinidad.<\/p>\n<p>e) Los Vocales designados por los Bloques Legislativos del Honorable Concejo Deliberante que act&uacute;en en el Directorio de la Caja tendr&aacute;n voz pero no voto.<\/p>\n<p><u>Art&iacute;culo 5&ordm;.-<\/u> El mandato de los vocales mencionados en el articulo 3&ordm; incs. c) y d) durar&aacute;n 2 (dos) a&ntilde;os pudiendo ser reelectos por una vez consecutiva.<\/p>\n<p>Los vocales suplentes remplazar&aacute;n a los titulares en caso de ausencia temporaria o definitiva con sus mismas facultades.<\/p>\n<p>Si luego de incorporado el suplente vacara una vocal&iacute;a deber&aacute; dentro de los 60 (sesenta) d&iacute;as, practicarse una nueva elecci&oacute;n de titular y suplente hasta la finalizaci&oacute;n del mandato del reemplazado.<\/p>\n<p><u>Art&iacute;culo 27&ordm;.-<\/u> a) Practicar los descuentos jubilatorios correspondientes sobre las remuneraciones del personal afiliado y depositarlo, dentro de los 23 (veintitr&eacute;s) d&iacute;as de practicados, en la cuenta que al efecto tenga la Caja en una entidad financiera reconocida. Si no se efectuare el dep&oacute;sito pasadas 48 (cuarenta y ocho) horas h&aacute;biles de vencido el plazo establecido, deber&aacute; abonar una multa equivalente al promedio diario que se deduzca de la tasa activa m&aacute;s costosa que tenga en ese momento Banco Naci&oacute;n por d&iacute;a, del valor total a depositar por la Municipalidad m&aacute;s los intereses correspondientes.<\/p>\n<p>b) Liquidar la Contribuci&oacute;n Patronal, que le corresponde como empleadora, seg&uacute;n est&aacute; Ordenanza, prevista en el inciso b), del Art&iacute;culo 22&ordm;, en igual fecha que los sueldos del personal y depositar las mismas dentro de los (23) d&iacute;as de practicadas en una cuenta bancaria que al efecto deber&aacute; tener la Caja, en una entidad financiera reconocida.&rdquo;<\/p>\n<p><b><u>Art&iacute;culo 2&ordm;.-<\/u><\/b> Comun&iacute;quese, reg&iacute;strese, publ&iacute;quese y arch&iacute;vese.-<\/p>\n<div>&nbsp;<\/div>\n<p><span>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/span>Nogoy&aacute;, Sala de Sesiones, 20 de febrero de 2.006.-<\/p>\n<div>&nbsp;<\/div>\n<p>Aprobado por unanimidad en general y particular &ndash; sobre tablas<\/p>\n<p><span class=\"texto\"><a href=\"\/userfiles\/file\/hcd\/2006\/O-0743.pdf\"><img decoding=\"async\" alt=\"\" border=\"0\" src=\"\/img\/pdf_icon.gif\" \/> Ordenanza N&ordm; 0743<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modifica Ord 502 ( Caja de Jubilaciones Municipal ). Directorio,<br \/>\nmandato, descuento jubilatorio, contribuci\u00f3n patronal.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-2916","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2916"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/2916\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}