{"id":10669,"date":"2025-11-19T11:39:11","date_gmt":"2025-11-19T14:39:11","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=10669"},"modified":"2025-11-19T11:39:11","modified_gmt":"2025-11-19T14:39:11","slug":"ordenanza-no-1528","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2025\/11\/19\/ordenanza-no-1528\/","title":{"rendered":"Ordenanza N\u00ba 1528"},"content":{"rendered":"\n<p style=\"text-align:right\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ordenanza&nbsp; N\u00ba&nbsp;\n1.528<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTOS<\/strong>:<\/p>\n\n\n\n<p>La Caja Municipal de Jubilados y Pensionados de Nogoy\u00e1 requiere una\nampliaci\u00f3n del Presupuesto de Gastos y Recursos del a\u00f1o 2025.<\/p>\n\n\n\n<p>La modificaci\u00f3n presupuestaria se justifica en mayores recursos generados\npor las inversiones realizadas en el Mercado de Valores, acompa\u00f1ados al\nincremento del Tipo de Cambio del d\u00f3lar en el transcurso del a\u00f1o,\nincrement\u00e1ndose el rubro Diferencia de Cambio por el incremento en el valor\nnominal de las inversiones.<\/p>\n\n\n\n<p>Estos mayores valores ser\u00e1n destinados a la adquisici\u00f3n de Cajas Navide\u00f1as\nque se entregan a los afiliados de nuestra Caja, empleados, jubilados y\npensionados, aumentando la partida de gastos, Gastos Generales y a las partidas\nHonorarios Profesionales, Personal Planta Permanente, Beneficios Jubilatorios y\nBeneficios Pensionados, Gas; as\u00ed mismo el rubro que m\u00e1s impacta es el de\nBeneficios para Jubilados y Pensionados el cual se ha incrementado de manera\nconsiderable en funci\u00f3n de lo presupuestado, ya que no solo dicho aumento fue\nacompa\u00f1ado por el aumento de los haberes, sino por la cantidad de jubilados que\nse han producido este a\u00f1o.<\/p>\n\n\n\n<p>Por estos motivos, se requiere una ampliaci\u00f3n presupuestaria.<\/p>\n\n\n\n<p><strong>Por ello,<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE DEL MUNICIPIO DE NOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON FUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00ba.-<\/strong> Ampl\u00edese en\nla suma de PESOS SEISCIENTOS NUEVE MILLONES CIEN MIL CON CERO CENTAVOS\n($609.100.000,00) el total de Recursos de la Caja Municipal de Jubilados y\nPensionados de Nogoy\u00e1 para el a\u00f1o 2025 y, por tanto, est\u00edmese en la suma de\nPESOS TRECE MIL QUINIENTOS CINCUENTA Y CUATRO MILLONES SEISCIENTOS CINCUENTA\nMIL CON CERO CENTAVOS ($13.554.650.000,00) el total de Recursos del Presupuesto\nGeneral para el a\u00f1o 2025.-<\/p>\n\n\n\n<p><strong>Art\u00edculo 2\u00ba.-<\/strong> Ampl\u00edese en\nla suma de PESOS SEISCIENTOS NUEVE MILLONES CIEN MIL CON CERO CENTAVOS\n($609.100.000,00) el Presupuesto General de Gastos de la Caja Municipal de\nJubilados y Pensionados de Nogoy\u00e1 para el a\u00f1o 2025 y, por tanto, f\u00edjese en la\nsuma de PESOS TRECE MIL QUINIENTOS CINCUENTA Y CUATRO MILLONES SEISCIENTOS\nCINCUENTA MIL CON CERO CENTAVOS ($13.554.650.000,00) el total de Presupuesto General\nde Gastos del 2025.-<\/p>\n\n\n\n<p><strong>Art\u00edculo 3\u00ba.-<\/strong> De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">Nogoy\u00e1, Sala de\nsesiones, 19 de Noviembre de 2025.-<\/p>\n\n\n\n<p>Aprobado\npor unanimidad, en general y en particular &#8211; Sobre tablas.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampliaci\u00f3n del Presupuesto del Ejercicio 2025  de la Caja de Jubilaciones de Nogoya <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-10669","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10669"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10669\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}