{"id":10533,"date":"2025-08-13T07:05:53","date_gmt":"2025-08-13T10:05:53","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=10533"},"modified":"2025-08-13T07:05:53","modified_gmt":"2025-08-13T10:05:53","slug":"ordenanza-no-1510","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2025\/08\/13\/ordenanza-no-1510\/","title":{"rendered":"Ordenanza N\u00ba 1510"},"content":{"rendered":"\n<p style=\"text-align:right\"><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Ordenanza N\u00ba&nbsp;\n1.510<\/strong><\/p>\n\n\n\n<p><strong>FUNDAMENTACI\u00d3N:<\/strong><\/p>\n\n\n\n<p>El Departamento Ejecutivo Municipal,\njunto a la Comisi\u00f3n del Parque Industrial Nogoy\u00e1, se encuentra llevando\nadelante tareas de regularizaci\u00f3n de amanzanamiento, mensuras y consolidaci\u00f3n\nde dominio en favor de terceros dentro del mismo. <\/p>\n\n\n\n<p>En dicho marco se han aprobado las\nmensuras de algunas de las manzanas que lo integran, resultando necesario\navanzar con la escritura declarativa que determine formalmente dichas manzanas.\n<\/p>\n\n\n\n<p>Este amanzanamiento permitir\u00e1 a los\nadquirentes de lotes mediante boleto de compraventa, que hubieren cumplido con\ntodas las condiciones establecidas en las distintas ordenanzas, proyectos e\ninstrumentos respectivos, realizar las mensuras individuales de los lotes y su\nposterior escrituraci\u00f3n. <\/p>\n\n\n\n<p>Estos actos resultan esenciales para\ngarantizar seguridad jur\u00eddica, transparencia y orden registral en el Parque\nIndustrial de Nogoy\u00e1. <\/p>\n\n\n\n<p>Si bien la administraci\u00f3n del Patrimonio\nMunicipal corresponde al Departamento Ejecutivo, los actos que impliquen\ndisposici\u00f3n o afectaci\u00f3n del dominio requieren autorizaci\u00f3n expresa del Concejo\nDeliberante, y el amanzanamiento al suponer una modificaci\u00f3n de la matr\u00edcula\noriginal, requerir\u00eda esta autorizaci\u00f3n. <\/p>\n\n\n\n<p>En esta etapa, se trata de actos\npreparatorios -no traslativos a particulares- consistentes en escrituraciones a\nnombre de la Municipalidad, con fines de ordenamiento dominial. <\/p>\n\n\n\n<p><strong>Por ello, <\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE\nDEL MUNICIPIO DE NOGOY\u00c1<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>SANCIONA CON\nFUERZA DE<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>ORDENANZA<\/strong><\/p>\n\n\n\n<p><strong>ART\u00cdCULO 1\u00b0:<\/strong> Autor\u00edcese al\nDepartamento Ejecutivo Municipal a la firma de las escrituras declarativas de\namanzanamiento del Parque Industrial de la ciudad de Nogoy\u00e1, conforme a los\nplanos aprobados y aquellos que en el futuro sean aprobados por la Direcci\u00f3n\nGeneral de Catastro y\/ o dem\u00e1s organismos competentes. &#8211;<\/p>\n\n\n\n<p><strong>ART\u00cdCULO 2\u00b0:<\/strong> La presente\nautorizaci\u00f3n comprende todos los actos necesarios para la inscripci\u00f3n registral\nde las escrituras de amanzanamiento del Parque Industrial a nombre del\nMunicipio. <\/p>\n\n\n\n<p><strong>ART\u00cdCULO 3\u00b0:<\/strong> El Departamento\nEjecutivo deber\u00e1 remitir a este Cuerpo copia de las escrituras inscriptas, una\nvez finalizado cada tr\u00e1mite, a efectos de su toma de conocimiento. <\/p>\n\n\n\n<p><strong>ART\u00cdCULO 4\u00b0: <\/strong>De forma. \u2013<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Nogoy\u00e1,\nSala de sesiones, 13 de agosto de 2025.-<\/p>\n\n\n\n<p>Aprobado por unanimidad, en general y en particular. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autorizar al D.E.M. .a la firma de escrituras declarativas de amanzanamiento del Parque Industrial.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-10533","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10533"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10533\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}