{"id":10384,"date":"2025-05-07T07:49:30","date_gmt":"2025-05-07T10:49:30","guid":{"rendered":"https:\/\/nuevo.nogoya.gob.ar\/?p=10384"},"modified":"2025-05-07T07:49:30","modified_gmt":"2025-05-07T10:49:30","slug":"ordenanza-no-1488","status":"publish","type":"post","link":"https:\/\/web.nogoya.gob.ar\/index.php\/2025\/05\/07\/ordenanza-no-1488\/","title":{"rendered":"Ordenanza N\u00ba 1488"},"content":{"rendered":"\n<p style=\"text-align:right\"><strong>&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;<\/strong><strong>&nbsp;&nbsp;&nbsp;&nbsp;Ordenanza N\u00ba&nbsp; 1.488<\/strong><\/p>\n\n\n\n<p>En fecha 13\/12\/24, el Dr. Carlos Augusto Lafferriere\npresenta nota por Mesa de Entradas de la Municipalidad, en representaci\u00f3n de\nlos Sres. Julio Eugenio Fern\u00e1ndez y Jorge Alberto Gallardo.<\/p>\n\n\n\n<p>En la nota de referencia pone en conocimiento al Municipio\nde una resoluci\u00f3n judicial por la que se adjudic\u00f3 en propiedad plena el \u201cexceso\nde t\u00edtulo\u201d que exist\u00eda en el inmueble Matr\u00edcula 101.490 con ubicaci\u00f3n catastral\nen Manzana 410 sobre calle Mart\u00edn Fierro, Belgrano, Calle P\u00fablica y Rocamora,\nplano de mensura 13.762. superficie total de 36.450, partida ATER 101.227.<\/p>\n\n\n\n<p>En virtud de esto, solicita que se modifiquen tanto la\nResoluci\u00f3n de la Secretar\u00eda de Obras y Servicios P\u00fablicos de fecha 27\/03\/19,\npor la que se otorga la factibilidad del Proyecto de Loteo de Fern\u00e1ndez y\nGallardo, como tambi\u00e9n la Ordenanza N\u00b0 1.270 de fecha 30\/09\/20, para que se\nsubsanen los datos catastrales que cambiaron con posterioridad a la emisi\u00f3n de\nlos mismos.<\/p>\n\n\n\n<p>Tras el pedido, la Comisi\u00f3n de Legislaci\u00f3n, Interpretaci\u00f3n\ny Educaci\u00f3n consulta a la Subsecretar\u00eda de Obras y Servicios P\u00fablicos a los\nfines de que informe si este excedente altera el proyecto de loteo presentado\noportunamente, espec\u00edficamente en lo que refiere a la donaci\u00f3n de calle y\nespacios verdes.<\/p>\n\n\n\n<p>La Subsecretar\u00eda de Obras y Servicios P\u00fablicos expresa que\nla nueva dimensi\u00f3n del loteo no altera ni afecta lo que se estableci\u00f3\noriginariamente en la Ordenanza N\u00b0 1.270 por lo que, lo aceptado en donaci\u00f3n\npara calle y espacios verdes, se mantiene conforme el proyecto inicial.<\/p>\n\n\n\n<p>As\u00ed mismo, esta misma dependencia procedi\u00f3 a modificarla\nResoluci\u00f3n de fecha 27\/03\/19, por lo que corresponde entonces, modificar la\nOrdenanza N\u00b0 1.270.<\/p>\n\n\n\n<p><strong>Por <\/strong><strong>ello,<\/strong><strong><\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>EL CONCEJO DELIBERANTE DEL MUNICIPIO DE &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong> NOGOY\u00c1 SANCIONA CON FUERZA DE<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; ORDENANZA<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>Art\u00edculo 1\u00b0 .\u2013 <\/strong>Modif\u00edquese el Art\u00edculo 1\u00b0 de la\nOrdenanza N\u00b0 1.270, que quedar\u00e1 redactado de la siguiente manera:\u201cArt\u00edculo 1\u00b0.-\nAc\u00e9ptese la Donaci\u00f3n de las superficies\npara calles, ensanchamiento y espacios verdes, determinados y detallados al\nConcejo Deliberante de la Ciudad de Nogoy\u00e1 seg\u00fan propuesta de los Se\u00f1ores Julio\nEugenio Fern\u00e1ndez DNI N\u00ba 23.299.871 y Jorge Alberto Gallardo DNI N\u00ba 13.146.375\nen referencia a \u201cProyecto\nde loteo-fraccionamiento\u00bb en inmueble de su propiedad sito entre calles Mart\u00edn Fierro, Rocamora,\nP\u00fablica (cerrada), y Ricardo Balb\u00edn \u2013 Prolongaci\u00f3n de Belgrano; Manzana N\u00ba 410,\nPlano de Mensura N\u00ba 13.762, Partida N\u00ba 101.227, con superficie de 36.450 m2 y\nde la voluntad irrevocable de donar 7032 m2 de terreno para el trazado de\ncalles nuevas, apertura de calles sin abrir y ensanche de frente sobre calle\nBelgrano en toda la extensi\u00f3n del loteo, adem\u00e1s de 3000 m2 para espacio p\u00fablico\ncorrespondiente al proyecto antes nombrado.\u201d.-<\/p>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Art\u00edculo 2\u00b0.\u2013 <\/strong>De forma.-<\/p>\n\n\n\n<p style=\"text-align:right\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nogoy\u00e1, Sala de sesiones, 7 de mayo de\n2025.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aprobado por unanimidad, en general y en particular &#8211; sobre tablas.<em><br> <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modif\u00edquese el Art\u00edculo 1\u00b0 de la Ordenanza N\u00b0 1.270.- Fern\u00e1ndez , Gallardo<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-10384","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-ordenanzas","7":"czr-hentry"},"_links":{"self":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10384"}],"version-history":[{"count":0,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/posts\/10384\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.nogoya.gob.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}